{"id":6759,"date":"2026-05-10T23:14:02","date_gmt":"2026-05-10T22:14:02","guid":{"rendered":"https:\/\/tiredofboys.com\/?p=6759"},"modified":"2026-05-12T10:20:23","modified_gmt":"2026-05-12T09:20:23","slug":"lighea-ser-o-primeiro-homem-depois-de-8-anos","status":"publish","type":"post","link":"https:\/\/tiredofboys.com\/pt-br\/lighea-ser-o-primeiro-homem-depois-de-8-anos\/","title":{"rendered":"Lighea &#8211; ser o primeiro homem depois de 8 anos"},"content":{"rendered":"<div style='text-align:center' class='yasr-auto-insert-visitor'><!--Yasr Visitor Votes Shortcode--><div id='yasr_visitor_votes_fa1ca97e665a4' class='yasr-visitor-votes'><div class=\"yasr-custom-text-vv-before yasr-custom-text-vv-before-6759\">Click to rate this post!<\/div><div id='yasr-vv-second-row-container-fa1ca97e665a4'\r\n                                        class='yasr-vv-second-row-container'><div id='yasr-visitor-votes-rater-fa1ca97e665a4'\r\n                                      class='yasr-rater-stars-vv'\r\n                                      data-rater-postid='6759'\r\n                                      data-rating='0'\r\n                                      data-rater-starsize='24'\r\n                                      data-rater-readonly='false'\r\n                                      data-rater-nonce='3cd8c05a83'\r\n                                      data-issingular='false'\r\n                                    ><\/div><div class=\"yasr-vv-stats-text-container\" id=\"yasr-vv-stats-text-container-fa1ca97e665a4\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\"\r\n                                   class=\"yasr-dashicons-visitor-stats\"\r\n                                   data-postid=\"6759\"\r\n                                   id=\"yasr-stats-dashicon-fa1ca97e665a4\">\r\n                                   <path d=\"M18 18v-16h-4v16h4zM12 18v-11h-4v11h4zM6 18v-8h-4v8h4z\"><\/path>\r\n                               <\/svg><span id=\"yasr-vv-text-container-fa1ca97e665a4\" class=\"yasr-vv-text-container\">[Total: <span id=\"yasr-vv-votes-number-container-fa1ca97e665a4\">0<\/span>  Average: <span id=\"yasr-vv-average-container-fa1ca97e665a4\">0<\/span>]<\/span><\/div><div id='yasr-vv-loader-fa1ca97e665a4' class='yasr-vv-container-loader'><\/div><\/div><div id='yasr-vv-bottom-container-fa1ca97e665a4'\r\n                              class='yasr-vv-bottom-container'\r\n                              style='display:none'><\/div><\/div><!--End Yasr Visitor Votes Shortcode--><\/div><div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"523\" height=\"1024\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-523x1024.png\" alt=\"\" class=\"wp-image-6764\" srcset=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-523x1024.png 523w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-153x300.png 153w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-768x1504.png 768w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-785x1536.png 785w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-1046x2048.png 1046w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-720x1410.png 720w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-580x1136.png 580w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-320x627.png 320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-1320x2584.png 1320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-scaled.png 1308w\" sizes=\"auto, (max-width: 523px) 100vw, 523px\" \/><\/figure>\n<\/div>\n<p>Esguia.<br\/>Tez clara.<br\/>Cabelos lisos que caem suavemente sobre os ombros.<br\/>Um tra\u00e7o de l\u00e1pis preto nos olhos, para alongar o olhar e torn\u00e1-lo mais misterioso, quase eg\u00edpcio.<br\/>Ela me envia tr\u00eas fotos.<br\/>Primeira foto: um vestidinho vermelho simples, digno, usado na esperan\u00e7a de agradar.<br\/>Segunda foto: jeans branco e top preto.<br\/>Terceira foto: vestidinho preto, com bordados de renda, sensual mas rigoroso.<br\/>Em todas as tr\u00eas ela n\u00e3o olha para a c\u00e2mera, mas para o celular com o qual est\u00e1 tirando uma selfie no espelho.<br\/>Ela as tirou para mim: para me perguntar qual dos tr\u00eas looks usar hoje \u00e0 noite, no nosso primeiro encontro. O meu Tinder date de hoje \u00e0 noite (a hist\u00f3ria \u00e9 de alguns meses atr\u00e1s, antes de eu conhecer a Ruiva).  <span style=\"color: #cc0000;\"><span style=\"color: #020202;\" class=\"stk-highlight\">Uma garota que \u2014 em vez de sair com o primeiro look que encontra \u2014 te pede conselhos sobre qual usar j\u00e1 \u00e9 uma exce\u00e7\u00e3o estat\u00edstica na civiliza\u00e7\u00e3o do Tinder swipe autom\u00e1tico.<\/span> <\/span><\/p>\n\n<p><strong>Eu<\/strong>: &#8220;<em><span style=\"color: #f00069;\" class=\"stk-highlight\">Coloca o segundo, aquele de renda<\/span><\/em>&#8220;<br\/><strong>Ela<\/strong>: &#8220;<em><span style=\"color: #7a4cc4;\" class=\"stk-highlight\">Concordo<\/span><\/em>&#8220;<\/p>\n\n<p>Poucas comunica\u00e7\u00f5es essenciais. Pouca leveza. Escreve-se o necess\u00e1rio para organizar a log\u00edstica, deixando para o encontro o prazer da descoberta.<br\/>Local: cocktail bar em Mil\u00e3o. Ela encara 40 minutos de carro para chegar. Nenhum pedido de Uber. Eu me ofere\u00e7o para busc\u00e1-la. Ela me responde &#8220;<em><span style=\"color: #7a4cc4;\" class=\"stk-highlight\">n\u00e3o precisa, eu vou por conta pr\u00f3pria<\/span><\/em>&#8220;.      <\/p>\n\n<p><span style=\"color: #0f0e17;\" class=\"stk-highlight\">L\u00e1 vem ela chegando: est\u00e1 usando o vestido combinado e sapatos fechados (n\u00e3o lembro se coturnos ou Dr. Martens). Sempre dou uma olhada no cal\u00e7ado de uma mulher, lembrando do que li quando garoto numa obra de Freud. O pai da psican\u00e1lise sustentava que a mulher v\u00ea no pr\u00f3prio p\u00e9 a met\u00e1fora simb\u00f3lica do p\u00eanis\u2026 Ok, conhecemos bem o velho tarado: via paus em todo lugar\u2026 mas de vez em quando ele acertava. Freud l\u00ea na escolha do sapato a usar um ind\u00edcio revelador da sexualidade subjacente: um sapato aberto, com muita pele \u00e0 mostra, sugere uma busca de encontro; uma sapatilha essencial, uma sexualidade natural, infantil; o salto agulha, uma sexualidade mais agressiva. E o coturno?     Bom, o coturno s\u00f3 pode sugerir fechamento, desejo de manter a sexualidade como um componente escondido, problem\u00e1tico, a ser reprimido. <\/span><span style=\"color: #cc0000;\"><span style=\"color: #0f0e17;\" class=\"stk-highlight\">Os sapatos s\u00e3o o curr\u00edculo er\u00f3tico exposto publicamente: a pessoa caminha dentro da pr\u00f3pria sexualidade a cada minuto, sem nem saber<\/span><\/span><span style=\"color: #0f0e17;\" class=\"stk-highlight\">.<br\/><\/span><span style=\"color: #000000;\" class=\"stk-highlight\">Todo esse racioc\u00ednio acontece na minha mente em menos de meio segundo, enquant<\/span>o deixo cair um olhar sobre os cal\u00e7ados dela. E termina com um pensamento: tio Sigmundo, o que pensaria de um homem com mais de 70 pares de sapatos, dos quais 20 sociais, mas que usa sempre os mesmos tr\u00eas? Como descreveria a sexualidade de um homem que veste frequentemente total black, mas confia o toque distintivo do seu estilo a sapatos colorid\u00edssimos, chamativos e muitas vezes de formas peculiares? E que evita cuidadosamente usar sapatos com cadar\u00e7os\u2026 porque n\u00e3o gosta de cadar\u00e7os? Como a corda do arco esticada por dois extremos cada vez mais distantes, \u00e9 interessante essa tens\u00e3o entre a busca cont\u00ednua por novidade na compra e o h\u00e1bito no uso; entre o amor secreto pela cerim\u00f4nia e sua nega\u00e7\u00e3o p\u00fablica, entre a cor gritante e o understatement do corpo.    <\/p>\n\n<p>Mas, <em>direto ao ponto!<\/em>, recebo a minha convidada e a escolto sorrindo at\u00e9 o sof\u00e1. Ela est\u00e1 sorridente, mas parece um pouco tensa. Eu comento isso.  <\/p>\n\n<p><strong>Lighea<\/strong>: &#8220;<em><span style=\"color: #7a4cc4;\" class=\"stk-highlight\">Confesso que voc\u00ea \u00e9 o meu primeiro date<\/span><\/em>&#8220;.<br\/><strong>Eu<\/strong>: &#8220;<em><span style=\"color: #f00069;\" class=\"stk-highlight\">Da semana?<\/span><\/em>&#8220;<br\/><strong>Lighea<\/strong>: &#8220;<em><span style=\"color: #7a4cc4;\" class=\"stk-highlight\">De sempre! Acabei de terminar depois de 8 anos de relacionamento! <\/span><\/em>&#8220;<br\/><strong>Eu<\/strong>: &#8220;<em><span style=\"color: #f00069;\" class=\"stk-highlight\">8 anos? Mas voc\u00ea mal passou dos vinte! <\/span><\/em>&#8220;<br\/><strong>Lighea<\/strong>: &#8220;<em><span style=\"color: #7a4cc4;\" class=\"stk-highlight\">Sim, eu estive em um relacionamento que durou toda a minha vida adulta e at\u00e9 alguns anos da minha adolesc\u00eancia. Nunca sa\u00ed em encontros, muito menos usando aplicativos. N\u00e3o sei como funciona!  <\/span><\/em>&#8220;<\/p>\n\n<p>Olho para ela em sil\u00eancio por um instante, fingindo \u2014 como um novo Atlas \u2014 ter o mundo sobre os ombros. Depois sorrio para ela e, com um tom caloroso e sincero, digo: <\/p>\n\n<p>&#8220;<em><span style=\"color: #f00069;\" class=\"stk-highlight\">Estou honrado por voc\u00ea ter me escolhido como seu primeiro date. \u00c9 uma grande responsabilidade ser o seu primeiro. Voc\u00ea fez bem em me contar. Eu costumo ser muito direto, mas tomarei um cuidado especial com voc\u00ea. Se em qualquer momento algo te incomodar, me diga    <\/span><\/em>&#8220;.<br\/>Sempre sorrindo, fa\u00e7o o disclaimer: &#8220;<em><span style=\"color: #f00069;\" class=\"stk-highlight\">e, enfim, n\u00e3o \u00e9 que tenhamos que terminar na cama: pode muito bem ser apenas um papo leve e divertido<\/span><\/em>&#8220;.<br\/>Curioso que toda vez que digo essa frase, a garota acaba de quatro no meu sof\u00e1 em 2 horas e 23 minut<span style=\"color: #0f0e17;\" class=\"stk-highlight\">os. <\/span><span style=\"color: #cc0000;\"><span style=\"color: #0f0e17;\" class=\"stk-highlight\">Provavelmente existe uma f\u00f3rmula matem\u00e1tica que ainda aguarda o seu Riemann.<\/span><\/span><\/p>\n\n<p>Com interesse sincero, pergunto sobre a hist\u00f3ria anterior dela.<br\/>Ela me conta um pouco sobre o ci\u00fame absurdo do ex dela.<br\/><strong>Eu<\/strong>: &#8220;<em><span style=\"color: #f00069;\" class=\"stk-highlight\">bem, ent\u00e3o se ele soubesse que voc\u00ea est\u00e1 aqui comigo hoje \u00e0 noite, n\u00e3o ficaria nada feliz<\/span><\/em>&#8220;<br\/><strong>Lei<\/strong>: &#8220;<em><span style=\"color: #7a4cc4;\" class=\"stk-highlight\">n\u00e3o, mas fica tranquilo: ele n\u00e3o pode te fazer nada. Foi deportado para o exterior <\/span><\/em>&#8220;.<br\/><strong>Eu<\/strong>: &#8220;<em><span style=\"color: #f00069;\" class=\"stk-highlight\">como assim, deportado? E voc\u00ea me diz isso assim, com toda essa nonchalance? <\/span><\/em>&#8220;<br\/><strong>Lei<\/strong>: &#8220;<em><span style=\"color: #7a4cc4;\" class=\"stk-highlight\">sim, n\u00e3o saberia como dizer de outro jeito<\/span><\/em>&#8220;<br\/><strong>Eu<\/strong>: &#8220;<em><span style=\"color: #f00069;\" class=\"stk-highlight\">hum, se me permite um conselho, talvez seja melhor n\u00e3o dizer isso logo no primeir\u00edssimo encontro. E \u2014 por favor \u2014 por que ele foi deportado? <\/span><\/em>&#8220;<br\/><strong>Lei<\/strong>: &#8220;<em><span style=\"color: #7a4cc4;\" class=\"stk-highlight\">agress\u00e3o por ci\u00fames<\/span><\/em>&#8220;<br\/><strong>Eu<\/strong>: &#8220;<em><span style=\"color: #f00069;\" class=\"stk-highlight\">ah, agress\u00e3o por ci\u00fames! Hum! Fant\u00e1stico!  <\/span><\/em>&#8221; Olho em volta, cauteloso. &#8220;<em><span style=\"color: #f00069;\" class=\"stk-highlight\">Olha, n\u00e3o diga isso tamb\u00e9m!<\/span><\/em>&#8220;<br\/>Rimos. <span style=\"color: #cc0000;\"><span style=\"color: #000000;\" class=\"stk-highlight\">Rimos porque, caso contr\u00e1rio, ter\u00edamos que levantar e ir embora; e nenhum de n\u00f3s tem a menor inten\u00e7\u00e3o disso.<\/span><\/span><\/p>\n\n<p>Apesar de ter pouco mais de 20 anos, Lighea \u00e9 um vinho antigo, nobre, com mais estrutura do que a sua garrafa empoeirada possa sugerir. Uma garrafa aberta hoje, ap\u00f3s pouco menos de 10 anos de repouso em uma adega escura e \u00famida.  <span style=\"color: #cc0000;\"><span style=\"color: #0f0e17;\" class=\"stk-highlight\">Um Donnafugata esquecido no fundo da prateleira de um wine bar que insistia em servir Prosecco para todo mundo.<\/span><\/span> Intinto uma hist\u00f3ria atormentada, mas prefiro n\u00e3o ser direto demais nas perguntas: Lighea \u00e9 uma garota que quer viver, n\u00e3o um caso para se ter pena.<\/p>\n\n<p>Com Lighea, tudo \u00e9 um n\u00e3o dito. Tudo \u00e9 subcomunicado, inoculado, transmitido nas premissas. Olho para aqueles olhos escuros e leio a sombra de hist\u00f3rias nunca contadas, viv\u00eancias profundas e certamente nada simples. Nela vejo uma grande dignidade e uma grande coragem. E tamb\u00e9m uma bela bunda, que apalpo quase imediatamente.    <\/p>\n\n<p>Conto sobre mim. Rimos e relaxamos. Ela me pergunta se eu a acompanho l\u00e1 fora para um cigarro.<br\/>Ela se senta no murete, de pernas abertas, com a saia longa cobrindo tudo. Enquanto falamos de cigarros, minhas m\u00e3os deslizam para baixo da saia. Generosas, sobem pelas coxas, pela parte interna, e param no psoas (caro leitor, n\u00e3o sabe onde fica o psoas? \u00c9 por isso que voc\u00ea n\u00e3o transa! Estude!). Ela continua falando fingindo que nada est\u00e1 acontecendo, mas a voz fica mais quente, o tom sobe meia oitava.<br\/>Ap\u00f3s poucos segundos \u2014 ainda enquanto falo \u2014 minhas m\u00e3os recome\u00e7am a se mover, ora sobem, ora descem. O olhar dela se acende, seus olhinhos escuros me pedem para subir. Eu, Magnificamente, finjo que n\u00e3o entendo e continuo falando.<br\/>Apenas o tempo necess\u00e1rio para ela se acostumar e subo r\u00e1pido em dire\u00e7\u00e3o ao vale do \u00c9den. Vou direto, afasto a calcinha e encosto sabiamente a ponta do meu dedo indicador.        <br\/><strong>Eu<\/strong>: &#8220;<em><span style=\"color: #f00069;\" class=\"stk-highlight\">voc\u00ea est\u00e1 encharcada. Por tr\u00e1s dessa express\u00e3o de desapego ser\u00e1fico, uma porquinha se contorce de desejo <\/span><\/em>&#8220;<br\/><strong>Ela<\/strong>, sussurrando: &#8220;<em><span style=\"color: #7a4cc4;\" class=\"stk-highlight\">SIMMM!<\/span><\/em>&#8220;<br\/>Como a corda que se tensiona violentamente com o afastamento dos dois extremos do arco, assim a tens\u00e3o entre nossos olhares sobe exponencialmente.<br\/>A cada respira\u00e7\u00e3o.<br\/>A cada meia palavra.<br\/>Normalmente eu ficaria ali conversando, cozinhando-a em fogo brando, \u00e0s vezes intensificando o seu prazer, \u00e0s vezes negando-o. Mas ela \u00e9 aut\u00eantica, sincera, transparente, honesta. E me quer desesperadamente dentro dela. E quem sou eu para negar isso a ela?<br\/>Levo-a de volta para dentro, n\u00e3o digo nada, ela pega as coisas dela depressa e corremos para pagar.<br\/>Sa\u00edmos do local direto para a minha casa.   <br\/><strong>Eu<\/strong>: &#8220;<em><span style=\"color: #f00069;\" class=\"stk-highlight\">vamos dar um pulo de cinco minutos na minha casa, s\u00f3 para voc\u00ea provar aquele vinho de que te falei, e depois sa\u00edmos de novo<\/span><\/em>&#8220;.<br\/>Aqui, um momento did\u00e1tico para os jovens machinhos (voc\u00eas, mulheres, podem pular o que segue).<\/p>\n\n<p>O trajeto entre o bar e a casa \u00e9, sem d\u00favida, o mais perigoso. Ambos sabem para onde v\u00e3o e por qu\u00ea.  Mas cuidado para n\u00e3o ser expl\u00edcito: mata a tens\u00e3o e libera aquilo que, na cena do dating, se chama LMR \u2014 Last Minute Resistance, ou tamb\u00e9m conhecida como &#8220;Defesa Anti-Vadia&#8221;. <span style=\"color: #cc0000;\"><span style=\"color: #0f0e17;\" class=\"stk-highlight\">Mystery (sim, aquele da cartola e do Game) escreveu meio manual sobre isso.<\/span><\/span><\/p>\n\n<p>Por mais que eu me divirta refutando as teses turbo-feministas da minha amiga Lella, \u00e9 ineg\u00e1vel que a sociedade exerce uma press\u00e3o estrondosa sobre a sexualidade feminina. Desde tempos imemoriais, a sexualidade feminina foi temida, hostilizada, controlada.  Bastava meia palavra, um comportamento errado e pronto: a pobre mo\u00e7a acabava ostracizada, exclu\u00edda, apontada como vadia e com a vida arruinada.<br\/>Hoje n\u00e3o \u00e9 mais assim (talvez estejamos no oposto, na verdade), mas no inconsciente coletivo e na cultura permaneceu a mem\u00f3ria at\u00e1vica disso. <span style=\"color: #cc0000;\"><span style=\"color: #000000;\" class=\"stk-highlight\">O paradoxo da modernidade: a mulher livre que \u2014 para poder se entregar \u2014 ainda precisa fingir que n\u00e3o quer. Tr\u00eas mil anos de B\u00edblia, Conc\u00edlio de Trento e sogras n\u00e3o se sacodem em duas gera\u00e7\u00f5es de MeToo. <\/span><\/span><br\/>Consequentemente, apesar de ambos quererem transar, ser expl\u00edcito neste momento muitas vezes faz a mulher sentir que parece puta demais e manda tudo para o espa\u00e7o.<br\/>Especialmente com aqueles homens moralistas, que passaram o encontro todo reclamando que n\u00e3o existem mais mulheres como antigamente\u2026 mas eu pergunto: voc\u00eas s\u00e3o burros? N\u00e3o digo para fazerem como eu (que mostro fotos das minhas ex e as desafio a n\u00e3o serem vadias o suficiente para me merecerem), mas tamb\u00e9m n\u00e3o precisam se castrar sozinhos.<br\/>Portanto, fa\u00e7am como eu, usem uma desculpa super \u00f3bvia (quase no n\u00edvel da cole\u00e7\u00e3o de borboletas) e ver\u00e3o que, assim que chegarem em casa, ela pular\u00e1 em cima de voc\u00eas como uma sugar baby na \u00faltima bolsa Chanel em promo\u00e7\u00e3o. <\/p>\n\n<p>Par\u00eanteses fechado, podemos continuar. (Ok, mo\u00e7as para quem eu disse para pular esta parte\u2026 sabemos muito bem que voc\u00eas leram tudo! N\u00e3o h\u00e1 melhor maneira de fazer uma mulher fazer algo do que dizer para ela n\u00e3o fazer. Hehe). <\/p>\n\n<p>Bom, o resto voc\u00eas podem imaginar: plug anal (primeira vez, diz ela). Transa no sof\u00e1. Um pouco de ardor e muitos carinhos.<br\/>Enquanto todo o corpo dan\u00e7a, do assoalho p\u00e9lvico ao esternocleidomastoideo (\u2026 como, o que \u00e9 isso? Garotos, voc\u00eas querem entender que precisam estudar!), eu olho para ela.<br\/>Vejo-a livre, exploradora, consciente de si, entregando-se a mim como o meu contador quando me pede conselhos sobre como pagar menos impostos.<br\/>Agora ela est\u00e1 feliz. Mas sei o que vai acontecer. Vai acontecer que, enquanto volta para casa, ela vai se sentir um pouco suja. N\u00e3o vai se reconhecer por ter se entregado t\u00e3o r\u00e1pido. Vai me dizer que eu corri demais. E vai projetar em mim o que foi ela quem desejou, como se fosse culpa minha.<br\/>Como com a <a href=\"https:\/\/tiredofboys.com\/pt-br\/tag\/tettedolci\/\" data-type=\"post_tag\" data-id=\"115\">PeitinhosDoces<\/a>, lembram? Com o agravante de que \u2014 tendo acabado de sair de um relacionamento sufocante \u2014 ela sentir\u00e1 necessidade de tomar um pouco de ar.<br\/>Mas Lighea \u00e9 uma mulher inteligente e profunda. Espero que ela volte. No fundo, mostrei a ela apenas 1 % do que poder\u00edamos explorar juntos.          <\/p>\n\n<p>A riaccompagno in auto e la vedo allontanarsi nell\u2019orizzonte milanese.<\/p>\n\n<p>Duas vidas se encontraram.<\/p>\n\n<p>Duas vidas se tocaram em um orgasmo.<\/p>\n\n<p>Duas vidas se afastaram.<\/p>\n\n<p>Veremos.<\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><!--Yasr Visitor Votes Shortcode--><div id='yasr_visitor_votes_456e5fe6a6a1a' class='yasr-visitor-votes'><div class=\"yasr-custom-text-vv-before yasr-custom-text-vv-before-6759\">Click to rate this post!<\/div><div id='yasr-vv-second-row-container-456e5fe6a6a1a'\r\n                                        class='yasr-vv-second-row-container'><div id='yasr-visitor-votes-rater-456e5fe6a6a1a'\r\n                                      class='yasr-rater-stars-vv'\r\n                                      data-rater-postid='6759'\r\n                                      data-rating='0'\r\n                                      data-rater-starsize='24'\r\n                                      data-rater-readonly='false'\r\n                                      data-rater-nonce='3cd8c05a83'\r\n                                      data-issingular='false'\r\n                                    ><\/div><div class=\"yasr-vv-stats-text-container\" id=\"yasr-vv-stats-text-container-456e5fe6a6a1a\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\"\r\n                                   class=\"yasr-dashicons-visitor-stats\"\r\n                                   data-postid=\"6759\"\r\n                                   id=\"yasr-stats-dashicon-456e5fe6a6a1a\">\r\n                                   <path d=\"M18 18v-16h-4v16h4zM12 18v-11h-4v11h4zM6 18v-8h-4v8h4z\"><\/path>\r\n                               <\/svg><span id=\"yasr-vv-text-container-456e5fe6a6a1a\" class=\"yasr-vv-text-container\">[Total: <span id=\"yasr-vv-votes-number-container-456e5fe6a6a1a\">0<\/span>  Average: <span id=\"yasr-vv-average-container-456e5fe6a6a1a\">0<\/span>]<\/span><\/div><div id='yasr-vv-loader-456e5fe6a6a1a' class='yasr-vv-container-loader'><\/div><\/div><div id='yasr-vv-bottom-container-456e5fe6a6a1a'\r\n                              class='yasr-vv-bottom-container'\r\n                              style='display:none'><\/div><\/div><!--End Yasr Visitor Votes Shortcode--><\/div>","protected":false},"excerpt":{"rendered":"<p>Click to rate this post! [Total: 0 Average: 0] Esguia.Tez clara.Cabelos lisos que caem suavemente sobre os ombros.Um tra\u00e7o de l\u00e1pis preto nos olhos, para alongar o olhar e torn\u00e1-lo mais misterioso, quase eg\u00edpcio.Ela me envia tr\u00eas fotos.Primeira foto: um vestidinho vermelho simples, digno, usado na esperan\u00e7a de agradar.Segunda foto: jeans branco e top preto.Terceira [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6766,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[156],"tags":[],"class_list":["post-6759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"featured_image_urls_v2":{"full":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-scaled.png",1308,2560,false],"thumbnail":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-150x150.png",150,150,true],"medium":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-153x300.png",153,300,true],"medium_large":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-768x1504.png",720,1410,true],"large":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-523x1024.png",523,1024,true],"1536x1536":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-785x1536.png",785,1536,true],"2048x2048":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-1046x2048.png",1046,2048,true],"typology-cover":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-scaled.png",1308,2560,false],"typology-a":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-720x1410.png",720,1410,true],"typology-b":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-580x1136.png",580,1136,true],"typology-c":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-320x627.png",320,627,true],"mailpoet_newsletter_max":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_5pugdq5pugdq5pug-clean-1320x2584.png",1320,2584,true]},"post_excerpt_stackable_v2":"<p>Click to rate this post! [Total: 0 Average: 0] Esguia.Tez clara.Cabelos lisos que caem suavemente sobre os ombros.Um tra\u00e7o de l\u00e1pis preto nos olhos, para alongar o olhar e torn\u00e1-lo mais misterioso, quase eg\u00edpcio.Ela me envia tr\u00eas fotos.Primeira foto: um vestidinho vermelho simples, digno, usado na esperan\u00e7a de agradar.Segunda foto: jeans branco e top preto.Terceira foto: vestidinho preto, com bordados de renda, sensual mas rigoroso.Em todas as tr\u00eas ela n\u00e3o olha para a c\u00e2mera, mas para o celular com o qual est\u00e1 tirando uma selfie no espelho.Ela as tirou para mim: para me perguntar qual dos tr\u00eas looks usar hoje\u2026<\/p>\n","category_list_v2":"<a href=\"https:\/\/tiredofboys.com\/pt-br\/category\/sem-categoria\/\" rel=\"category tag\">Sem categoria<\/a>","author_info_v2":{"name":"MagniFico","url":"https:\/\/tiredofboys.com\/pt-br\/author\/magnifico\/"},"comments_num_v2":"0 comments","yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/posts\/6759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/comments?post=6759"}],"version-history":[{"count":6,"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/posts\/6759\/revisions"}],"predecessor-version":[{"id":6797,"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/posts\/6759\/revisions\/6797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/media\/6766"}],"wp:attachment":[{"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/media?parent=6759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/categories?post=6759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/tags?post=6759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}