{"id":4747,"date":"2021-02-18T21:51:00","date_gmt":"2021-02-18T20:51:00","guid":{"rendered":"https:\/\/tiredofboys.com\/horror-quando-dei-uma-espiada-no-celular-da-olhos-de-mel\/"},"modified":"2026-04-10T01:45:29","modified_gmt":"2026-04-10T00:45:29","slug":"horror-quando-dei-uma-espiada-no-celular-da-olhos-de-mel","status":"publish","type":"post","link":"https:\/\/tiredofboys.com\/pt-br\/horror-quando-dei-uma-espiada-no-celular-da-olhos-de-mel\/","title":{"rendered":"[HORROR] Quando espiei o celular da Inominada"},"content":{"rendered":"<div style='text-align:center' class='yasr-auto-insert-visitor'><!--Yasr Visitor Votes Shortcode--><div id='yasr_visitor_votes_a972a6ab565d6' class='yasr-visitor-votes'><div class=\"yasr-custom-text-vv-before yasr-custom-text-vv-before-4747\">Click to rate this post!<\/div><div id='yasr-vv-second-row-container-a972a6ab565d6'\r\n                                        class='yasr-vv-second-row-container'><div id='yasr-visitor-votes-rater-a972a6ab565d6'\r\n                                      class='yasr-rater-stars-vv'\r\n                                      data-rater-postid='4747'\r\n                                      data-rating='0'\r\n                                      data-rater-starsize='24'\r\n                                      data-rater-readonly='false'\r\n                                      data-rater-nonce='3cd8c05a83'\r\n                                      data-issingular='false'\r\n                                    ><\/div><div class=\"yasr-vv-stats-text-container\" id=\"yasr-vv-stats-text-container-a972a6ab565d6\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\"\r\n                                   class=\"yasr-dashicons-visitor-stats\"\r\n                                   data-postid=\"4747\"\r\n                                   id=\"yasr-stats-dashicon-a972a6ab565d6\">\r\n                                   <path d=\"M18 18v-16h-4v16h4zM12 18v-11h-4v11h4zM6 18v-8h-4v8h4z\"><\/path>\r\n                               <\/svg><span id=\"yasr-vv-text-container-a972a6ab565d6\" class=\"yasr-vv-text-container\">[Total: <span id=\"yasr-vv-votes-number-container-a972a6ab565d6\">0<\/span>  Average: <span id=\"yasr-vv-average-container-a972a6ab565d6\">0<\/span>]<\/span><\/div><div id='yasr-vv-loader-a972a6ab565d6' class='yasr-vv-container-loader'><\/div><\/div><div id='yasr-vv-bottom-container-a972a6ab565d6'\r\n                              class='yasr-vv-bottom-container'\r\n                              style='display:none'><\/div><\/div><!--End Yasr Visitor Votes Shortcode--><\/div><div class=\"wp-block-image is-resized is-style-rounded\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"694\" height=\"1024\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03-694x1024.png\" alt=\"Cena de horror - espiar o celular da Innominata\" class=\"wp-image-1601\" srcset=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03-694x1024.png 694w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03-203x300.png 203w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03-768x1133.png 768w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03-720x1062.png 720w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03-580x856.png 580w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03-320x472.png 320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03.png 892w\" sizes=\"auto, (max-width: 694px) 100vw, 694px\" \/><\/figure>\n<\/div>\n<p>S\u00e1bado \u00e0 noite. Estou trancado em casa h\u00e1 uma semana. Sacos do Deliveroo emergem da bagun\u00e7a espalhada por todo o loft, rel\u00edquias arqueol\u00f3gicas que testemunham as refei\u00e7\u00f5es da \u00faltima semana. A camada mais alta, e portanto historicamente mais recente, \u00e9 composta pelas embalagens de rem\u00e9dios. Pois \u00e9, <strong>peguei COVID-19.<\/strong>    <\/p>\n\n<p><strong>Eu j\u00e1 tinha colocado o risco na conta.<\/strong> No in\u00edcio da pandemia, muitos desistiram de qualquer encontro e se limitaram ao m\u00ednimo necess\u00e1rio de rela\u00e7\u00f5es profissionais. Eu decidi fazer o contr\u00e1rio: nada de escrit\u00f3rio, nada de mercado, nenhuma viagem de transporte p\u00fablico, nada de nada, exceto&#8230; as mulheres. Eu continuaria com meus encontros galantes, com as garotas que conheci no Tinder ou no Seeking.   <\/p>\n\n<p><strong>&#8220;Se eu tiver que morrer de alguma coisa, que morra de amor, de sexo, transando, vivendo<\/strong>&#8230; n\u00e3o enquanto estou indo para o trabalho ou fazendo compras&#8221;, pensei.<\/p>\n<div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/media.giphy.com\/media\/QZsb7H2QVGpbX4FHWA\/giphy.gif\" alt=\"Imagem do relato de horror do celular da Innominata\"\/><figcaption class=\"wp-element-caption\">O dating nos tempos da Covid-19.<\/figcaption><\/figure>\n<\/div>\n<p>Alguns de voc\u00eas dir\u00e3o <strong>\u00abBem feito!\u00bb.<\/strong><\/p>\n\n<p>Mas n\u00e3o, porque sei com certeza onde peguei o Covid&#8230; no escrit\u00f3rio, no \u00fanico dia em que fui at\u00e9 l\u00e1 para um almo\u00e7o de trabalho! <br\/>Por sorte, no momento n\u00e3o tenho quase nenhum sintoma. Vamos torcer. <\/p>\n\n<p>Com o isolamento domicili\u00e1rio, finalmente tenho tempo de te atualizar sobre a Inominada.<\/p>\n\n<p>Foi um m\u00eas muito intenso e cheio de reviravoltas.<br\/>Como contei <a href=\"https:\/\/tiredofboys.com\/report\/ma-che-fine-ha-fatto-occhi-di-miele\/\">aqui<\/a>, no nosso \u00faltimo encontro a Inominada apareceu com 7 horas de atraso\u2026 mas totalmente irresist\u00edvel. Entre n\u00f3s criou-se uma liga\u00e7\u00e3o \u00fanica, que deu origem a uma experi\u00eancia poderos\u00edssima. Foi uma noite estranha, cheia de sentimentos contradit\u00f3rios: <strong>por um lado senti amor puro, como poucas vezes antes; por outro \u00f3dio pela falta de respeito demonstrada.<\/strong> Fodemos como nunca, com uma sintonia nunca antes sentida, at\u00e9 \u00e0s 5 da manh\u00e3. A cona dela tem este poder m\u00e1gico de apagar qualquer discuss\u00e3o, ou quase. Confio que a intensidade alcan\u00e7ada a leve finalmente a deixar de se desalinhar quando recebe amor e a comportar-se com o respeito m\u00ednimo que exijo de qualquer pessoa.    <\/p>\n\n<p>Convido-a para jantar novamente depois de dois dias. Ela chega com uma hora e meia de atraso. Fico puto, brigamos. Depois fazemos as pazes. Transamos mal pra caramba. Vamos para a cama.     <\/p>\n\n<p>Durante a noite, a inquietude cresce.<br\/>Ela dorme ao meu lado. Abra\u00e7a o travesseiro com ternura, como se quisesse transmitir todo o carinho do mundo.  <br\/>Penso comigo mesmo.<\/p>\n\n<p>&#8220;Paolo, at\u00e9 quando voc\u00ea vai se enganar?&#8221;<br\/>&#8220;Meu Deus, quem \u00e9?&#8221;<br\/>&#8220;Sou o Yogi Tsuru&#8230;&#8221;<br\/><strong>&#8220;O pinto guru! Mas \u00e9 a primeira vez que voc\u00ea fala!&#8221;<\/strong><\/p>\n<div class=\"wp-block-image is-resized is-style-default\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/11\/giphy_guru.gif\" alt=\"Screenshot inquietante do celular\" class=\"wp-image-492\" style=\"width:358px;height:auto\"\/><figcaption class=\"wp-element-caption\">Yogi Tsuru, o meu pinto Guru.<\/figcaption><\/figure>\n<\/div>\n<p>&#8220;Desta vez n\u00e3o posso mais calar-me. Repito a pergunta: <strong>at\u00e9 quando queres continuar a ser enganado?<\/strong> Ora escreve-te, ora desaparece. N\u00e3o respeita um \u00fanico hor\u00e1rio. Na outra noite chegou 7 horas atrasada!    E tu? <br\/>Voc\u00ea nem piscou. Mandou v\u00e1rias pessoas para a puta que pariu por muito menos&#8221;. <\/p>\n\n<p>&#8220;Tsuru, voc\u00ea sabe, ela n\u00e3o est\u00e1 pronta para se apaixonar. Toda vez que dou amor a ela, ela se afasta. N\u00e3o fiquei puto porque entendi que \u00e9 a estrat\u00e9gia de defesa dela, ela simplesmente precisa de tempo, n\u00e3o est\u00e1 pronta para se entregar totalmente&#8221;.<br\/>&#8220;<strong><span style=\"text-decoration: underline;\">Precisar de tempo \u00e9 a maior das ilus\u00f5es<\/span><\/strong>. <br\/>Ela n\u00e3o est\u00e1 apaixonada, nunca vai se apaixonar. <br\/>Quando a gente transa, ela fica felic\u00edssima se voc\u00ea a chama de puta e de dep\u00f3sito de porra, mas&#8230; assim que voc\u00ea a chama de &#8216;amor&#8217;, ela trava! Tenta chamar a PeitosDoces de amor e v\u00ea que rea\u00e7\u00e3o oposta voc\u00ea ter\u00e1&#8221;.<br\/>Verdade. Mas&#8230; <br\/>&#8220;&#8230;Mas de qualquer forma o sexo com ela \u00e9 bom demais, eu poderia ficar com ela s\u00f3 por isso. Quem disse que precisa necessariamente se apaixonar?&#8221;<br\/>&#8220;Claro. Voc\u00ea poderia. Mas tem um requisito fundamental: o respeito. Voc\u00ea sabe que ela transa com outros&#8221;.<br\/>&#8220;Bem, eu tamb\u00e9m transo com outras e voc\u00ea n\u00e3o s\u00f3 sabe bem disso como&#8230; \u00e9 c\u00famplice! No fundo \u00e9 voc\u00ea quem entra ou \u00e9 chupado, meu caro pinto. Eu sou simplesmente o seu carregador&#8221;.<br\/>&#8220;N\u00f3s transamos, mas&#8230; n\u00f3s falamos. N\u00e3o contamos historinhas. N\u00e3o mentimos. E, acima de tudo, n\u00e3o desrespeitamos o tempo dela. Porra, voc\u00ea se faz chamar de MagniFico e permite que uma garota chegue com 7 \u2014 sete! \u2014 horas de atraso? E, principalmente, hoje ela tamb\u00e9m chegou uma hora e meia depois do hor\u00e1rio previsto\u2026 \u00c9 demais&#8221;.<\/p>\n\n<p>Sei que o meu Pisello tem raz\u00e3o, mas quero provas. A Innominata dorme \u00e0 minha direita, tranquila, com a sua cara de deusa do sexo e anjinho ao mesmo tempo.  Retiro a m\u00e3o da sua bunda e&#8230; pego o celular dela. <br\/>Eu tinha visto de relance o c\u00f3digo dela.<br\/><strong>&#8220;Yogi, tive uma ideia. Vou olhar o celular dela&#8221;.<\/strong><br\/>&#8220;Burrice sem tamanho! <br\/>1. \u00c9 uma falta de respeito. <br\/>2. Qualquer coisa que voc\u00ea encontrar, n\u00e3o poder\u00e1 reclamar com ela.<br\/>3. \u00c0s vezes as coisas parecem mais graves e diferentes quando est\u00e3o escritas no chat&#8221;.<br\/>&#8220;Voc\u00ea faz o seu papel de Pinto e foca em transar, isso aqui \u00e9 comigo&#8221;.<\/p>\n\n<p>Desbloqueio o celular.<br\/>Procuro meu nome nas conversas com os amigos dela.<br\/>Leio um chat de alguns dias atr\u00e1s, com um cara que ela chama de &#8220;amor&#8221;&#8230;<br\/>Ela faz a lista das pessoas com quem est\u00e1 saindo simultaneamente. Tem eu e&#8230; outros tr\u00eas caras.<br\/>De todos ela diz que estamos perdendo a cabe\u00e7a por ela.<br\/>O amigo dela d\u00e1 conselhos que prefiro n\u00e3o relatar, mas que me incomodam.<br\/>Mas o auge \u00e9 descobrir que <strong>quando ela atrasou 7 horas\u2026 estava com outro!<\/strong> <\/p>\n\n<p>&#8220;Yogi, voc\u00ea tinha raz\u00e3o\u2026&#8221;.<br\/>Ele n\u00e3o responde. Evidentemente n\u00e3o tem mais nada a dizer.<br\/>Eu imaginava que ela pegava outros paus por a\u00ed e me contava mentiras sobre isso (e tudo bem). Mas as 7 horas de atraso com direito a deboche (\u00abEu peguei no sono!\u00bb) no s\u00e1bado foi inaceit\u00e1vel. E na noite anterior, quando ela tinha dado mais um atraso (mesmo que de \u201capenas\u201d 2 horas), eu a tinha enfrentado seriamente e ela at\u00e9 tentou sustentar que tinha raz\u00e3o.<br\/>Tudo bem, mas <strong>n\u00e3o existem os pressupostos de respeito e sinceridade para lidar comigo<\/strong>, muito menos para que eu possa me entregar a um relacionamento.   <\/p>\n\n<p>O estranho \u00e9 que\u2026 estou calm\u00edssimo. <br\/>N\u00e3o estou puto. <br\/>De um certo ponto de vista, me sinto at\u00e9 libertado.<br\/>Talvez a verdade seja que n\u00e3o me sinto pronto para me jogar totalmente. Gosto muito dela, mas&#8230; n\u00e3o sinto que posso confiar nela. <strong>E, provavelmente, n\u00e3o sinto que posso confiar em mim.<\/strong><br\/>Essa rela\u00e7\u00e3o n\u00e3o tem futuro. <br\/>Amanh\u00e3 mando ela pastar.<\/p>\n\n<p>Durmo, finalmente sereno, por um par de horas.<br\/>Ela acorda.<br\/>Claro que n\u00e3o posso dizer que dei uma espiada no celular dela. Finjo que nada aconteceu.<br\/>Tento transar com ela uma \u00faltima vez, mas&#8230; o Yogi Tsuru n\u00e3o quer saber de nada. <br\/>Ela est\u00e1 com pressa, tem que ir trabalhar.<br\/>Ela est\u00e1 estranha, \u00e9 como se tivesse percebido algo.<br\/>Dou um beijo nela na porta.<br\/>Ela continua me escrevendo enquanto vai para o trabalho. <br\/><\/p>\n\n<p>N\u00e3o aguento mais.<br\/>Mando um \u00e1udio dizendo que n\u00e3o consegui dormir pensando nas constantes faltas de respeito dela com os hor\u00e1rios, no fato de que tenho certeza de que ela transa com outros e que a vejo sempre online no site de encontros onde nos conhecemos.<br\/>Enfim, agrade\u00e7o pelo trecho de caminho percorrido juntos e me despe\u00e7o para sempre, dizendo que <strong>n\u00e3o existem condi\u00e7\u00f5es para continuarmos nos vendo.<\/strong><br\/>Ela me responde assim:<\/p>\n<div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"706\" height=\"1024\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/IMG_BB99723D72B1-1-706x1024.jpeg\" alt=\"Foto pessoal do relato de horror do celular\" class=\"wp-image-1595\" srcset=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/IMG_BB99723D72B1-1-706x1024.jpeg 706w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/IMG_BB99723D72B1-1-207x300.jpeg 207w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/IMG_BB99723D72B1-1-768x1114.jpeg 768w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/IMG_BB99723D72B1-1-720x1045.jpeg 720w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/IMG_BB99723D72B1-1-580x842.jpeg 580w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/IMG_BB99723D72B1-1-320x464.jpeg 320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/IMG_BB99723D72B1-1.jpeg 1000w\" sizes=\"auto, (max-width: 706px) 100vw, 706px\" \/><\/figure>\n<\/div>\n<p>Eu esperava uma mensagem sincera.<br\/>Obviamente n\u00e3o respondo.<\/p>\n\n<p>E am\u00e9m.<br\/>Termina assim a grande hist\u00f3ria com a Inominada.<br\/>Ehm&#8230;<br\/>Mais ou menos&#8230;<br\/>Digamos&#8230;<br\/>Ok, <strong>passada uma semana volto a contact\u00e1-la e&#8230; <a href=\"https:\/\/tiredofboys.com\/report\/il-trappolone-ovvero-occhi-di-miele-reloaded\/\" data-type=\"post\" data-id=\"1598\">tudo muda!<\/a><\/strong><\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><!--Yasr Visitor Votes Shortcode--><div id='yasr_visitor_votes_5a2aa5e6626d6' class='yasr-visitor-votes'><div class=\"yasr-custom-text-vv-before yasr-custom-text-vv-before-4747\">Click to rate this post!<\/div><div id='yasr-vv-second-row-container-5a2aa5e6626d6'\r\n                                        class='yasr-vv-second-row-container'><div id='yasr-visitor-votes-rater-5a2aa5e6626d6'\r\n                                      class='yasr-rater-stars-vv'\r\n                                      data-rater-postid='4747'\r\n                                      data-rating='0'\r\n                                      data-rater-starsize='24'\r\n                                      data-rater-readonly='false'\r\n                                      data-rater-nonce='3cd8c05a83'\r\n                                      data-issingular='false'\r\n                                    ><\/div><div class=\"yasr-vv-stats-text-container\" id=\"yasr-vv-stats-text-container-5a2aa5e6626d6\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\"\r\n                                   class=\"yasr-dashicons-visitor-stats\"\r\n                                   data-postid=\"4747\"\r\n                                   id=\"yasr-stats-dashicon-5a2aa5e6626d6\">\r\n                                   <path d=\"M18 18v-16h-4v16h4zM12 18v-11h-4v11h4zM6 18v-8h-4v8h4z\"><\/path>\r\n                               <\/svg><span id=\"yasr-vv-text-container-5a2aa5e6626d6\" class=\"yasr-vv-text-container\">[Total: <span id=\"yasr-vv-votes-number-container-5a2aa5e6626d6\">0<\/span>  Average: <span id=\"yasr-vv-average-container-5a2aa5e6626d6\">0<\/span>]<\/span><\/div><div id='yasr-vv-loader-5a2aa5e6626d6' class='yasr-vv-container-loader'><\/div><\/div><div id='yasr-vv-bottom-container-5a2aa5e6626d6'\r\n                              class='yasr-vv-bottom-container'\r\n                              style='display:none'><\/div><\/div><!--End Yasr Visitor Votes Shortcode--><\/div>","protected":false},"excerpt":{"rendered":"<p>Click to rate this post! [Total: 0 Average: 0] S\u00e1bado \u00e0 noite. Estou trancado em casa h\u00e1 uma semana. Sacos do Deliveroo emergem da bagun\u00e7a espalhada por todo o loft, rel\u00edquias arqueol\u00f3gicas que testemunham as refei\u00e7\u00f5es da \u00faltima semana. A camada mais alta, e portanto historicamente mais recente, \u00e9 composta pelas embalagens de rem\u00e9dios. Pois [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4748,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[156],"tags":[167],"class_list":["post-4747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","tag-olhosdemel"],"featured_image_urls_v2":{"full":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03.png",892,1316,false],"thumbnail":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03-150x150.png",150,150,true],"medium":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03-203x300.png",203,300,true],"medium_large":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03-768x1133.png",720,1062,true],"large":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03-694x1024.png",694,1024,true],"1536x1536":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03.png",892,1316,false],"2048x2048":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03.png",892,1316,false],"typology-cover":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03.png",892,1316,false],"typology-a":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03-720x1062.png",720,1062,true],"typology-b":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03-580x856.png",580,856,true],"typology-c":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03-320x472.png",320,472,true],"mailpoet_newsletter_max":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2021\/03\/Schermata-2021-01-23-alle-17.38.03.png",892,1316,false]},"post_excerpt_stackable_v2":"<p>Click to rate this post! [Total: 0 Average: 0] S\u00e1bado \u00e0 noite. Estou trancado em casa h\u00e1 uma semana. Sacos do Deliveroo emergem da bagun\u00e7a espalhada por todo o loft, rel\u00edquias arqueol\u00f3gicas que testemunham as refei\u00e7\u00f5es da \u00faltima semana. A camada mais alta, e portanto historicamente mais recente, \u00e9 composta pelas embalagens de rem\u00e9dios. Pois \u00e9, peguei COVID-19. Eu j\u00e1 tinha colocado o risco na conta. No in\u00edcio da pandemia, muitos desistiram de qualquer encontro e se limitaram ao m\u00ednimo necess\u00e1rio de rela\u00e7\u00f5es profissionais. Eu decidi fazer o contr\u00e1rio: nada de escrit\u00f3rio, nada de mercado, nenhuma viagem de transporte p\u00fablico,\u2026<\/p>\n","category_list_v2":"<a href=\"https:\/\/tiredofboys.com\/pt-br\/category\/sem-categoria\/\" rel=\"category tag\">Sem categoria<\/a>","author_info_v2":{"name":"MagniFico","url":"https:\/\/tiredofboys.com\/pt-br\/author\/magnifico\/"},"comments_num_v2":"0 comments","yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/posts\/4747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/comments?post=4747"}],"version-history":[{"count":4,"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/posts\/4747\/revisions"}],"predecessor-version":[{"id":6342,"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/posts\/4747\/revisions\/6342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/media\/4748"}],"wp:attachment":[{"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/categories?post=4747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tiredofboys.com\/pt-br\/wp-json\/wp\/v2\/tags?post=4747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}