{"id":6622,"date":"2026-04-13T01:11:30","date_gmt":"2026-04-13T00:11:30","guid":{"rendered":"https:\/\/tiredofboys.com\/carta-a-xmas-baby-mi-hijo-sorpresa\/"},"modified":"2026-04-13T14:05:48","modified_gmt":"2026-04-13T13:05:48","slug":"carta-a-xmas-baby-mi-hijo-sorpresa","status":"publish","type":"post","link":"https:\/\/tiredofboys.com\/es\/carta-a-xmas-baby-mi-hijo-sorpresa\/","title":{"rendered":"Carta a XMas Baby&#8230; \u00a1mi hijo! (\u00a1Sorpresa!)"},"content":{"rendered":"<div style='text-align:center' class='yasr-auto-insert-visitor'><!--Yasr Visitor Votes Shortcode--><div id='yasr_visitor_votes_0dda91e605707' class='yasr-visitor-votes'><div class=\"yasr-custom-text-vv-before yasr-custom-text-vv-before-6622\">Click to rate this post!<\/div><div id='yasr-vv-second-row-container-0dda91e605707'\r\n                                        class='yasr-vv-second-row-container'><div id='yasr-visitor-votes-rater-0dda91e605707'\r\n                                      class='yasr-rater-stars-vv'\r\n                                      data-rater-postid='6622'\r\n                                      data-rating='0'\r\n                                      data-rater-starsize='24'\r\n                                      data-rater-readonly='false'\r\n                                      data-rater-nonce='3cd8c05a83'\r\n                                      data-issingular='false'\r\n                                    ><\/div><div class=\"yasr-vv-stats-text-container\" id=\"yasr-vv-stats-text-container-0dda91e605707\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\"\r\n                                   class=\"yasr-dashicons-visitor-stats\"\r\n                                   data-postid=\"6622\"\r\n                                   id=\"yasr-stats-dashicon-0dda91e605707\">\r\n                                   <path d=\"M18 18v-16h-4v16h4zM12 18v-11h-4v11h4zM6 18v-8h-4v8h4z\"><\/path>\r\n                               <\/svg><span id=\"yasr-vv-text-container-0dda91e605707\" class=\"yasr-vv-text-container\">[Total: <span id=\"yasr-vv-votes-number-container-0dda91e605707\">0<\/span>  Average: <span id=\"yasr-vv-average-container-0dda91e605707\">0<\/span>]<\/span><\/div><div id='yasr-vv-loader-0dda91e605707' class='yasr-vv-container-loader'><\/div><\/div><div id='yasr-vv-bottom-container-0dda91e605707'\r\n                              class='yasr-vv-bottom-container'\r\n                              style='display:none'><\/div><\/div><!--End Yasr Visitor Votes Shortcode--><\/div><div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"767\" height=\"1024\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-767x1024.png\" alt=\"Mi hijo XMas Baby\" class=\"wp-image-6614\" srcset=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-767x1024.png 767w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-225x300.png 225w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-768x1025.png 768w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-1151x1536.png 1151w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-1534x2048.png 1534w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-720x961.png 720w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-580x774.png 580w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-320x427.png 320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-1320x1762.png 1320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1.png 1792w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/><\/figure>\n<\/div>\n<p><em>Son<\/em> <em>las<\/em> <em>4<\/em> <em>de<\/em> <em>la noche.<\/em> <em>La<\/em> <em>luz<\/em> <em>del<\/em> <em>tel\u00e9fono<\/em> <em>me<\/em> <em>ilumina<\/em> <em>la<\/em> <em>cara<\/em> <em>como<\/em> <em>un<\/em> <em>interrogatorio.<\/em> <em>En<\/em> <em>Google<\/em> <em>acabo<\/em> <em>de<\/em> <em>buscar<\/em> <em>&#8220;c\u00f3mo<\/em> <em>se<\/em> <em>sostiene<\/em> <em>un<\/em> <em>reci\u00e9n nacido<\/em> <em>sin<\/em> <em>romperlo&#8221;.<\/em> <em>El<\/em> <em>segundo<\/em> <em>resultado<\/em> <em>es<\/em> <em>&#8220;c\u00f3mo<\/em> <em>se<\/em> <em>monta<\/em> <em>una<\/em> <em>cuna<\/em> <em>de Ikea<\/em> <em>sin<\/em> <em>blasfemar&#8221;.<\/em> <em>El<\/em> <em>tercero<\/em>  es  <em>un<\/em> <em>psic\u00f3logo.<\/em> <em>Quiz\u00e1s<\/em> <em>deber\u00eda<\/em> <em>empezar<\/em> <em>por<\/em> <em>el tercero.<\/em><br\/><em>Y s\u00ed, buena gente, \u00a1mi vida est\u00e1 cambiando!<br\/>Una noticia ha llegado, fat\u00eddica, con la energ\u00eda de un rayo que sacude un roble centenario, tatuando indeleblemente su recuerdo en la corteza quemada. \u00a1Voy a ser padre! <\/em><\/p>\n\n<p><em>He llamado a Filippo. Le he dicho que voy a ser padre. Un silencio tan largo que he comprobado si hab\u00eda colgado. Luego, con una voz que nunca le hab\u00eda o\u00eddo: &#8221;   <\/em>Por fin has dejado de renunciar a jugar<em>.&#8221; Pausa. &#8220;<\/em>Lo has hecho muy bien, Pablo<em>.&#8221; Y ha colgado. Filippo casi nunca dice &#8220;bien hecho&#8221;. Lo ha dicho dos veces en <\/em> <em>seis a\u00f1os. Esa era la segunda. <\/em> <br\/>Y<em> mientras miraba embobado el tel\u00e9fono, ha vuelto a llamar: &#8220;<\/em>\u00bfPuedo ser el padrino? \u00a1As\u00ed al menos uno en la familia crece bien! <em>&#8220;.<br\/>No estoy preparado para lo que me espera. No me queda m\u00e1s que hacer lo que hago cuando no s\u00e9 qu\u00e9 hacer: escribir. Te escribo directamente a ti, a mi hijo.  <\/em><\/p>\n\n<p>Querido beb\u00e9 que nacer\u00e1s dentro de 6 meses y 23 d\u00edas,<\/p>\n\n<p>Te escribo unas l\u00edneas para que puedas conocer c\u00f3mo era tu padre antes de que nacieras.<br\/>Se dice que la llegada de un beb\u00e9 reescribe profundamente el ADN de los padres, as\u00ed que seguramente el Paolo-despu\u00e9s-de-ti ser\u00e1 muy diferente del Paolo-antes-de-ti. Quiz\u00e1 ser\u00e9 menos temerario, m\u00e1s reflexivo, menos despreocupado. Me asusta un poco: no me veo burgu\u00e9s, cauto, prudente. Yo, el que tiene como lema &#8220;\u00a1Solo la Imaginaci\u00f3n como l\u00edmite!&#8221;. Pero ya no es tiempo de aventuras audaces&#8230; dentro de 6 meses habr\u00e1 algo extremadamente precioso que proteger: t\u00fa.<br\/>No esperaba tu llegada. Ya me hab\u00eda resignado a vivir una vida de soltero, entre fiestas, tr\u00edos florales y muchas cosas que ahora a\u00fan no puedes entender, pero \u2014conf\u00eda en m\u00ed\u2014 \u00a1son bastante divertidas! Como dicen Articolo 31 en &#8220;La Fidanzata&#8221;,      <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Mi vida es un casino<br\/>Cada noche en el club de King Mauri<br\/>Con los chicos de la banda<br\/>Conspirando como si se tratara de un atraco a un banco<br\/>Para cazar a la <strong>t\u00eda<\/strong> que llevar a la cama<br\/>Aunque no nos falta compa\u00f1\u00eda femenina<br\/>Se trata de aventureras extranjeras<br\/>Amores que resultan ser quimeras<br\/>Las puedes ver desaparecer<br\/>A la luz de la ma\u00f1ana como un sue\u00f1o<\/p>\n<\/blockquote>\n\n<p>Y sin embargo&#8230; \u00a1ahora cambia todo! \u00bfMe ves en el supermercado \u2014\u00a1una tienda f\u00edsica!\u2014 comprando pa\u00f1ales? \u00bfCocin\u00e1ndote la papilla, yo que pido hasta la sal por Deliveroo?   <br\/>Pero te confieso que&#8230; \u00a1no veo la hora!<br\/>Ser\u00e1 precioso cogerte en brazos reci\u00e9n nacido: ya veo tus ojos almendrados, como los de tu madre. Espero que heredes su piel clar\u00edsima y luminosa. Tendr\u00e1s sus ojos color cielo del Gran Ca\u00f1\u00f3n, de ese azul supersaturado que solo en Estados Unidos se ve. Yo te regalar\u00e9 mi naricita alejandrina, como la de las estatuas antiguas. Ser\u00e1s un peque\u00f1o dios griego, medio asi\u00e1tico, medio siciliano, un poco bronce de Riace, un poco <em>buddace<\/em> borracho, con ciudadan\u00eda americana y con dos sociedades offshore a tu nombre ya al nacer\u2026 \u00a1qu\u00e9 mezcla!<br\/>Me veo en las largas noches de invierno acun\u00e1ndote para que dejes de llorar. S\u00e9 que ese llanto me partir\u00e1 el coraz\u00f3n, salvo regenerarlo con la primera sonrisita p\u00edcara que me dediques.<br\/>Ser\u00e1 precioso verte crecer y hablar con los abuelos en siciliano, t\u00fa, con tu acento neoyorquino. Mojar tu chupete en el limoncello que, como sabr\u00e1s, es el licor favorito de tu madre.      <\/p>\n\n<h2 class=\"wp-block-heading\">Tu madre<\/h2>\n\n<p>Y precisamente de ella quer\u00eda hablarte.<br\/>Debes admirarla: no ser\u00e1 f\u00e1cil para ella abandonar todo y mudarse a Italia. Ella dice que no le pesa, que es algo que hace con gusto. Pero seguramente habr\u00e1 momentos de tristeza: Mil\u00e1n es bonita, pero no es su hogar.  <br\/><a href=\"https:\/\/tiredofboys.com\/es\/xmas-lady-el-amor-posible\/\">XMas Lady<\/a>, tu madre, me sorprendi\u00f3. No la vi venir. S\u00ed, es cierto, me gust\u00f3 de inmediato a primera vista. Pero nunca habr\u00eda imaginado que se convertir\u00eda en la madre de mis hijos.<br\/>Una mezcla imposible: italiana, rusa, jud\u00eda&#8230; tres pueblos en una sola mujer, hijo m\u00edo, \u00a1y ninguno de los tres se pone de acuerdo con los dem\u00e1s!<br\/>Recuerdo nuestra primera cita en el <a href=\"https:\/\/en.wikipedia.org\/wiki\/Hotel_Chelsea\" target=\"_blank\" rel=\"noopener\">Hotel Chelsea<\/a>, en Navidad de 2025, cuando incluso se hizo la interesante no acost\u00e1ndose conmigo la primera noche. Menos mal que ya no soy tan susceptible como antes. Y adem\u00e1s recuperamos con creces en Miami.<br\/>Deb\u00eda ser uno de esos flirteos vacacionales, una llamarada fuerte que se apaga al volver. Pero, en cambio, tu madre me sigui\u00f3 enseguida a Mil\u00e1n. Se fue volviendo cada vez m\u00e1s dulce y empez\u00f3 a instalarme en la mente la idea de tu posible llegada.       <\/p>\n\n<p>A primera vista es tan sumisa y complaciente. Se ha entregado completamente a m\u00ed, con confianza y un pellizco de temor, al probar cosas que nunca hab\u00eda probado. \u00a1Tendr\u00edas que ver la cara que puso la primera vez que le ped\u00ed anal! Ups, quiz\u00e1s no sea la mejor imagen que darle a un hijo de su madre\u2026 perdona, no tengo pr\u00e1ctica, \u00a1esto es nuevo para m\u00ed!   <br\/>Seguramente no falt\u00f3 el amor. Al menos, no hasta ahora. Me esperaba en casa, llena de amor y pasi\u00f3n.<br\/>Tendr\u00edas que verla cuando se desata en la pista de baile, cuando intenta bailar como yo y luego \u2014obviamente\u2014 lo niega.<br\/>Y tambi\u00e9n en la cama bailaba bien. Otra vez, perdona. Pero debo criarte como &#8220;masculo veru&#8221; (hombre de verdad), as\u00ed que estas cosas de todas formas tarde o temprano tendr\u00e9 que explic\u00e1rtelas&#8230; \u00bfQu\u00e9 m\u00e1s da? S\u00ed, bueno, quiz\u00e1 esperemos a que sepas caminar para darte los detalles.<br\/>Tu madre me &#8220;enga\u00f1\u00f3&#8221;, pero en el buen sentido&#8230; \u00a1y menos mal que lo hizo, si no t\u00fa no estar\u00edas aqu\u00ed con nosotros! No pens\u00e1bamos que pudiera quedarse embarazada, pero sucedi\u00f3. Y est\u00e1 bien as\u00ed.        <\/p>\n\n<h2 class=\"wp-block-heading\">Una idea muy poco ortodoxa<\/h2>\n\n<p>Adem\u00e1s tu madre tiene una idea de la familia que le dar\u00eda un infarto a un cura y un orgasmo a m\u00ed. Dijo que no le pesaba que yo viera tambi\u00e9n a otras, m\u00e1s bien, adoraba la idea de tener una &#8220;sister wife&#8221;, o sea que yo tuviera con el tiempo otra mujer con la que hacer un hijo y&#8230; \u00a1criar una bonita familia extendida! <\/p>\n\n<p>Esta idea me impact\u00f3 mucho, pero no por lujuria sino por un motivo m\u00e1s profundo: por una vez en la vida, \u00a1la primera!, me sent\u00ed totalmente visto y aceptado. Con mi necesidad de libertad, mi exuberante alegr\u00eda de vivir y mi guarrer\u00eda ancestral. Saber que pod\u00eda hacer esto no &#8220;a pesar&#8221; de mi pareja, sino con su completa bendici\u00f3n&#8230; me abri\u00f3 el coraz\u00f3n.<br\/>Pasaban los d\u00edas y esta idea excavaba en mi mente. Me gustaba de verdad, pero me parec\u00eda demasiado bueno para ser cierto. Decid\u00ed entonces llamar a mi madre, o sea tu abuela, para que me disuadiera.<br\/>Debes saber que la abuela desea desde tiempos inmemoriales un nietecito. Mis padres siempre han vivido en funci\u00f3n de los hijos (piensa que se mudaron a Mil\u00e1n por m\u00ed) pero&#8230; \u00a1con los nietos no han tenido suerte! De los tres hijos que tuvieron, uno es gay, la otra es lesbiana y el tercero \u2014yo\u2014 \u00a1soltero putero certificado!    <\/p>\n\n<h2 class=\"wp-block-heading\">La llamada a la abuela<\/h2>\n\n<p><strong>Yo<\/strong>: &#8220;Mam\u00e1, he conocido a una chica loca. Dice que me permite ir con otras, con tal de que tenga un hijo con ella.&#8221;<br\/><span style=\"color: #c62641;\" class=\"stk-highlight\"><strong>Mam\u00e1<\/strong>: &#8220;Bien, bien.&#8221;<\/span><br\/><strong>Yo<\/strong>: &#8220;\u00a1\u00bfPero c\u00f3mo bien?! \u00bfNo me dices que tenga cuidado? \u00bfQue no me f\u00ede?&#8221;<br\/><span style=\"color: #c62641;\" class=\"stk-highlight\"><strong>Mam\u00e1<\/strong>: &#8220;No, no, \u00a1conf\u00eda! \u00a1No lo pienses! \u00a1D\u00e9jala embarazada! \u00a1Salud!&#8221;<\/span><br\/><strong>Yo<\/strong>: &#8220;\u00a1Pero mam\u00e1!&#8221;<br\/><span style=\"color: #c62641;\" class=\"stk-highlight\"><strong>Mam\u00e1<\/strong>: &#8220;Pero no, \u00a1los hijos son bendiciones!&#8221;<\/span><br\/><strong>Yo<\/strong>: &#8220;Vale, pero \u00bfno tienes nada que recomendarme?&#8221;<br\/><span style=\"color: #c62641;\" class=\"stk-highlight\"><strong>Mam\u00e1<\/strong>: [lo piensa un momento] &#8220;S\u00ed, una cosa hay.&#8221;<\/span><br\/><strong>Yo<\/strong>: &#8220;\u00a1Eso, bien! \u00a1Dime! \u00a1Dame un consejo que me haga razonar!&#8221;<br\/><span style=\"color: #c62641;\" class=\"stk-highlight\"><strong>Mam\u00e1<\/strong>: &#8220;Si luego os separ\u00e1is y ella quiere volver a Nueva York, que quede claro que el hijo se queda aqu\u00ed con nosotros, \u00a1en Italia!&#8221;<\/span><br\/><strong>Yo<\/strong>: &#8230;<\/p>\n\n<p>Por mucho que pueda parecer todo tan extra\u00f1o, tu madre y yo conectamos enseguida. Hubo una qu\u00edmica fulminante, en la cama y fuera de ella. Ella empez\u00f3 a volverse adicta al sexo juntos, yo a tenerla a mi lado. Mira, con XMas Lady por fin me he sentido como un ni\u00f1o en Navidad.<br\/>Estaba pensando en invitar a todas las protagonistas del blog a tu bautizo. \u00a1Quiz\u00e1s podr\u00edas tener a la <a href=\"https:\/\/tiredofboys.com\/es\/category\/americanina\/\">Americanita<\/a> como t\u00eda (al menos habla tu idioma)! La <a href=\"https:\/\/tiredofboys.com\/es\/la-diosa-francesa-cinco-anos-despues\/\">Diosa Francesa<\/a> como madrina de estilo: te ense\u00f1ar\u00eda que el babero tiene que ir a juego con los zapatos. <a href=\"https:\/\/tiredofboys.com\/es\/pequenina-adios\/\">Peque\u00f1ita<\/a> como guardaespaldas: ay de quien te toque, esa te defiende a mordiscos. Invitemos tambi\u00e9n a Filippo, a ver si te sirve alg\u00fan consejo con las compa\u00f1eras de guarder\u00eda.      <\/p>\n\n<h2 class=\"wp-block-heading\">Thomas<\/h2>\n\n<p>\u00bfQuieres saber c\u00f3mo te llamar\u00e1s? Por tu nombre, discutimos durante dos semanas. Ella quer\u00eda un nombre ruso. Yo quer\u00eda un nombre italiano. \u00a1Al final elegimos Thomas! En honor a mi mejor amigo (y tambi\u00e9n a mi socio). No se lo digas, pero a mam\u00e1 le vend\u00ed el nombre como un augurio de que puedas ser como Santo Tom\u00e1s. Ya sabes que mam\u00e1 ama la Biblia (aunque siempre la lee con el plug que le regal\u00e9). Bueno, t\u00f3mate en serio este augurio: no creas en nada, todo es marketing. Te lo dice pap\u00e1, que es publicista.<br\/>Cree &#8220;solo&#8221; en el amor. Eso tambi\u00e9n es marketing pero \u2014mientras a\u00fan puedas creer en \u00e9l\u2014 es alucinante.          <\/p>\n\n<p>No veo la hora de que llegues. De tenerte sobre mi barriga, cubierto con la mantita negra que tantas chicas han usado, pero ahora\u2026 es solo tuya. Quiero sentir tu calor en mi pecho, emocionarme bes\u00e1ndote la frente tierna, mientras estoy aterrado de poder hacerle da\u00f1o a algo tan fr\u00e1gil, peque\u00f1o y grande al mismo tiempo.  <br\/>Quiero poner mi dedo \u00edndice \u00e1spero en tus manitas suav\u00edsimas y sentir que lo aprietas.<\/p>\n\n<p>Quiero hacer todo esto\u2026<\/p>\n\n<p>Pero no es posible.<\/p>\n\n<p>Porque no habr\u00e1 ninguna manita.<\/p>\n\n<p>Ninguna mantita sobre ti.<\/p>\n\n<p>No estar\u00e1s t\u00fa.<\/p>\n\n<p>Porque tu madre, <a href=\"https:\/\/tiredofboys.com\/es\/xmas-lady-el-amor-posible\/\">XMas Lady<\/a>, una noche de febrero recogi\u00f3 sus cosas y se fue. No te dir\u00e9 por qu\u00e9. No porque no lo sepa, sino porque no cambia nada. Lo que importa es que la puerta se cerr\u00f3, y con ella se fue todo esto.   <\/p>\n\n<p>Y t\u00fa, Thomas, mi XMas Baby de bonitos ojos azules almendrados&#8230; t\u00fa te has quedado aqu\u00ed, en esta carta, que es el \u00fanico lugar donde has estado jam\u00e1s.<\/p>\n\n<p>Duerme, peque\u00f1o.<\/p>\n\n<p>Que puedas so\u00f1ar con la espl\u00e9ndida vida que tu padre, poco Magn\u00edfico y muy Paolo, hab\u00eda imaginado para ti.<\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><!--Yasr Visitor Votes Shortcode--><div id='yasr_visitor_votes_026e095ae0070' class='yasr-visitor-votes'><div class=\"yasr-custom-text-vv-before yasr-custom-text-vv-before-6622\">Click to rate this post!<\/div><div id='yasr-vv-second-row-container-026e095ae0070'\r\n                                        class='yasr-vv-second-row-container'><div id='yasr-visitor-votes-rater-026e095ae0070'\r\n                                      class='yasr-rater-stars-vv'\r\n                                      data-rater-postid='6622'\r\n                                      data-rating='0'\r\n                                      data-rater-starsize='24'\r\n                                      data-rater-readonly='false'\r\n                                      data-rater-nonce='3cd8c05a83'\r\n                                      data-issingular='false'\r\n                                    ><\/div><div class=\"yasr-vv-stats-text-container\" id=\"yasr-vv-stats-text-container-026e095ae0070\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\"\r\n                                   class=\"yasr-dashicons-visitor-stats\"\r\n                                   data-postid=\"6622\"\r\n                                   id=\"yasr-stats-dashicon-026e095ae0070\">\r\n                                   <path d=\"M18 18v-16h-4v16h4zM12 18v-11h-4v11h4zM6 18v-8h-4v8h4z\"><\/path>\r\n                               <\/svg><span id=\"yasr-vv-text-container-026e095ae0070\" class=\"yasr-vv-text-container\">[Total: <span id=\"yasr-vv-votes-number-container-026e095ae0070\">0<\/span>  Average: <span id=\"yasr-vv-average-container-026e095ae0070\">0<\/span>]<\/span><\/div><div id='yasr-vv-loader-026e095ae0070' class='yasr-vv-container-loader'><\/div><\/div><div id='yasr-vv-bottom-container-026e095ae0070'\r\n                              class='yasr-vv-bottom-container'\r\n                              style='display:none'><\/div><\/div><!--End Yasr Visitor Votes Shortcode--><\/div>","protected":false},"excerpt":{"rendered":"<p>El Magn\u00edfico escribe una carta al hijo que nacer\u00e1 dentro de 6 meses de XMas Lady. Entre pa\u00f1ales, tr\u00edos y una abuela demasiado entusiasta, la carta m\u00e1s tierna y sorprendente del blog. <\/p>\n","protected":false},"author":1,"featured_media":6623,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[82,79],"tags":[239,260,93],"class_list":["post-6622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reporte","category-amor","tag-adios","tag-historias-reales","tag-xmaslady"],"featured_image_urls_v2":{"full":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1.png",1792,2392,false],"thumbnail":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-150x150.png",150,150,true],"medium":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-225x300.png",225,300,true],"medium_large":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-768x1025.png",720,961,true],"large":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-767x1024.png",720,961,true],"1536x1536":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-1151x1536.png",1151,1536,true],"2048x2048":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-1534x2048.png",1534,2048,true],"typology-cover":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1.png",1792,2392,false],"typology-a":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-720x961.png",720,961,true],"typology-b":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-580x774.png",580,774,true],"typology-c":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-320x427.png",320,427,true],"mailpoet_newsletter_max":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_yfcbrxyfcbrxyfcb-1-1320x1762.png",1320,1762,true]},"post_excerpt_stackable_v2":"<p>El Magn\u00edfico escribe una carta al hijo que nacer\u00e1 dentro de 6 meses de XMas Lady. Entre pa\u00f1ales, tr\u00edos y una abuela demasiado entusiasta, la carta m\u00e1s tierna y sorprendente del blog. <\/p>\n","category_list_v2":"<a href=\"https:\/\/tiredofboys.com\/es\/category\/reporte\/\" rel=\"category tag\">Reporte<\/a>, <a href=\"https:\/\/tiredofboys.com\/es\/category\/amor\/\" rel=\"category tag\">Amor<\/a>","author_info_v2":{"name":"MagniFico","url":"https:\/\/tiredofboys.com\/es\/author\/magnifico\/"},"comments_num_v2":"0 comments","yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/posts\/6622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/comments?post=6622"}],"version-history":[{"count":6,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/posts\/6622\/revisions"}],"predecessor-version":[{"id":6651,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/posts\/6622\/revisions\/6651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/media\/6623"}],"wp:attachment":[{"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/media?parent=6622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/categories?post=6622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/tags?post=6622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}