{"id":3750,"date":"2025-08-13T13:38:29","date_gmt":"2025-08-13T12:38:29","guid":{"rendered":"https:\/\/tiredofboys.com\/la-chica-bond-y-el-cicisbeo-yo\/"},"modified":"2026-04-10T01:45:45","modified_gmt":"2026-04-10T00:45:45","slug":"la-chica-bond-y-el-cicisbeo-yo","status":"publish","type":"post","link":"https:\/\/tiredofboys.com\/es\/la-chica-bond-y-el-cicisbeo-yo\/","title":{"rendered":"La chica Bond y el cicisbeo (\u00a1yo!)"},"content":{"rendered":"<div style='text-align:center' class='yasr-auto-insert-visitor'><!--Yasr Visitor Votes Shortcode--><div id='yasr_visitor_votes_a69c278d6b75d' class='yasr-visitor-votes'><div class=\"yasr-custom-text-vv-before yasr-custom-text-vv-before-3750\">Click to rate this post!<\/div><div id='yasr-vv-second-row-container-a69c278d6b75d'\r\n                                        class='yasr-vv-second-row-container'><div id='yasr-visitor-votes-rater-a69c278d6b75d'\r\n                                      class='yasr-rater-stars-vv'\r\n                                      data-rater-postid='3750'\r\n                                      data-rating='0'\r\n                                      data-rater-starsize='24'\r\n                                      data-rater-readonly='false'\r\n                                      data-rater-nonce='3cd8c05a83'\r\n                                      data-issingular='false'\r\n                                    ><\/div><div class=\"yasr-vv-stats-text-container\" id=\"yasr-vv-stats-text-container-a69c278d6b75d\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\"\r\n                                   class=\"yasr-dashicons-visitor-stats\"\r\n                                   data-postid=\"3750\"\r\n                                   id=\"yasr-stats-dashicon-a69c278d6b75d\">\r\n                                   <path d=\"M18 18v-16h-4v16h4zM12 18v-11h-4v11h4zM6 18v-8h-4v8h4z\"><\/path>\r\n                               <\/svg><span id=\"yasr-vv-text-container-a69c278d6b75d\" class=\"yasr-vv-text-container\">[Total: <span id=\"yasr-vv-votes-number-container-a69c278d6b75d\">0<\/span>  Average: <span id=\"yasr-vv-average-container-a69c278d6b75d\">0<\/span>]<\/span><\/div><div id='yasr-vv-loader-a69c278d6b75d' class='yasr-vv-container-loader'><\/div><\/div><div id='yasr-vv-bottom-container-a69c278d6b75d'\r\n                              class='yasr-vv-bottom-container'\r\n                              style='display:none'><\/div><\/div><!--End Yasr Visitor Votes Shortcode--><\/div><div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"775\" height=\"1024\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-775x1024.png\" alt=\"Ilustraci&#xF3;n de la Bond Girl - portada del relato\" class=\"wp-image-3939\" srcset=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-775x1024.png 775w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-227x300.png 227w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-768x1015.png 768w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-1162x1536.png 1162w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-1550x2048.png 1550w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-720x951.png 720w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-580x766.png 580w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-320x423.png 320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-1320x1744.png 1320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e.png 1792w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><\/figure>\n<\/div>\n<p>\u00daltimamente en Tinder se encuentra de todo. \u00a1Incluso esp\u00edas! <br\/>Durante mis cl\u00e1sicos 5 minutos diarios de swipe, me llama la atenci\u00f3n su perfil. Tiene la piel muy clara, el pelo negr\u00edsimo, ojos claros, de un tono desva\u00eddo entre el verde y el azul. 26 a\u00f1os, declara que busca una relaci\u00f3n seria.<br\/>Rasgos de mujer del Este, con p\u00f3mulos marcados y mand\u00edbula importante. No la t\u00edpica mu\u00f1eca de adorno, sino una mujer que puede ganar Miss Ucrania y arrancarte el esternocleidomastoideo con un movimiento de Krav Maga.<br\/>Las fotos tienen un gusto exquisito, como esas fotos de autor de otros tiempos que tanto le gustan a Roberto, mi abogado. Cada pose est\u00e1 estudiada, cada movimiento del cuerpo es fruto de un gesto art\u00edstico. Se percibe que ella es la artista y no la modelo.<br\/>La descripci\u00f3n es de locos.     <\/p>\n<div class=\"wp-block-image is-style-default\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"530\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-10.23.54-1.png\" alt=\"Captura de conversaci&#xF3;n con la Bond Girl\" class=\"wp-image-2010\" srcset=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-10.23.54-1.png 576w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-10.23.54-1-300x276.png 300w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-10.23.54-1-320x294.png 320w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure>\n<\/div>\n<p>Uhm, no se entiende nada. En cualquier caso, est\u00e1 buena, as\u00ed que le doy <em>match<\/em>. Reescribo su descripci\u00f3n con otras palabras para imitar su estilo y activar un contacto, a\u00f1adiendo un par de intuiciones sobre ella:  <br\/><\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"1024\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-11.40.30-660x1024.png\" alt=\"Captura de conversaci&#xF3;n con la Bond Girl\" class=\"wp-image-2012\" srcset=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-11.40.30-660x1024.png 660w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-11.40.30-193x300.png 193w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-11.40.30-768x1191.png 768w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-11.40.30-990x1536.png 990w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-11.40.30-720x1117.png 720w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-11.40.30-580x900.png 580w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-11.40.30-320x496.png 320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-11.40.30.png 1060w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/figure>\n\n<p>Vabb\u00e9, el cl\u00e1sico calco con lenguaje vago para entablar rapport: el Tinder dating es un trabajo duro, pero alguien tiene que hacerlo.<br\/>Charlamos distra\u00eddamente un poco, entre un compromiso y otro, y al final le pido Instagram y WhatsApp.<br\/>Intento entender mejor a qui\u00e9n tengo delante. Es artista, frecuenta el mundo de la moda. Tiene una p\u00e1gina web a su nombre, con todos sus trabajos. Tiene un perfil de Instagram lleno de fotos art\u00edsticas en las que de vez en cuando aparece un cacho de culo, un muslo. Es un erotismo muy mental, muy construido, del que podr\u00eda gustarle a mi amiga Lella (yo soy m\u00e1s de chicas que las mujeres sofisticadas definen como &#8220;vulgares&#8221;, disimulando malamente el m\u00e1ximo grado de envidia femenina posible).    <\/p>\n\n<p>No tengo prisa por conocerla, en este momento mi agenda ya est\u00e1 bastante llena de mujeres, quiero entender si, m\u00e1s all\u00e1 de la est\u00e9tica, puede valer la pena, si es una persona con algo m\u00e1s, por lo que quiz\u00e1s perder la cabeza.<br\/>Hablamos de relaciones, de encuentros, de amor. Tiene una rutina muy estricta, que incluye gimnasio todos los d\u00edas, curso de italiano, piano. Habla italiano muy bien, para llevar aqu\u00ed poco m\u00e1s de un par de a\u00f1os. Es ucraniana, me cuenta que huy\u00f3 de la guerra. Me pregunto si ten\u00eda novio all\u00ed, antes de la guerra. Si \u00e9l sigue vivo, all\u00ed obligado por ley a combatir, mientras ella est\u00e1 aqu\u00ed haciendo fotos art\u00edsticas y teniendo citas en Tinder. Me acordar\u00e9 de hablar de ella a la pr\u00f3xima feminista mis\u00e1ndrica que hable de cuotas rosas y discriminaci\u00f3n de las mujeres en el trabajo. No me permito pedirle detalles, de todos modos: ver tu pa\u00eds en llamas debe ser una herida abierta y sangrante. Descubrir\u00e9 despu\u00e9s que, despu\u00e9s de venir a Italia, por amor se traslad\u00f3 a un fr\u00edo pa\u00eds del norte, donde am\u00f3 much\u00edsimo a su hombre, apoy\u00e1ndolo incluso cuando \u00e9l quer\u00eda estar con m\u00e1s mujeres. Ok, venga, \u00a1conozc\u00e1mosla \ud83d\ude42         <\/p>\n\n<h2 class=\"wp-block-heading\">Primera cita de cortejo<\/h2>\n\n<p>Tras una semana de chat, la invito a salir. Acepta encantada, pero me dice que quiere volver pronto a casa. Le digo que la habr\u00eda invitado a cenar pero que, si tiene restricciones de tiempo, podemos ir a tomar un aperitivo. &#8220;No, no, tranquilo. Te espero&#8221;.    Vale, ya hemos pillado el tipo: <em>cena y ven a buscarme a la puerta de casa<\/em>. <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"592\" height=\"1024\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-12.05.34-592x1024.png\" alt=\"Captura de conversaci&#xF3;n con la Bond Girl\" class=\"wp-image-2014\" style=\"width:413px;height:auto\" srcset=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-12.05.34-592x1024.png 592w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-12.05.34-173x300.png 173w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-12.05.34-768x1328.png 768w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-12.05.34-720x1245.png 720w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-12.05.34-580x1003.png 580w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-12.05.34-320x553.png 320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-12.05.34.png 836w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/><\/figure>\n<\/div>\n<p>Aclaremos enseguida un punto.<br\/>Me toca bastante los cojones el esquema tradicional donde el hombre corteja, demuestra, hace gestos llamativos y la mujer &#8211; nueva princesita &#8211; se lleva todas las atenciones. Creo que este modelo tradicional subcomunica &#8211; revisti\u00e9ndolo de galanter\u00eda &#8211; unos presupuestos venenosos: <\/p>\n\n<ul class=\"wp-block-list\">\n<li>La mujer es el premio, el hombre debe sud\u00e1rsela y\/o compr\u00e1rsela con regalos;<\/li>\n\n\n\n<li>La mujer vale a pesar de todo por lo que es. El hombre, al contrario, vale por lo que hace, dona, posee. <\/li>\n\n\n\n<li>El hombre debe demostrar gentileza, capacidad de protecci\u00f3n y cuidado. Lo que me parecer\u00eda bien, pero no se entiende por qu\u00e9 debe hacerlo desde el principio, con una t\u00eda que ni siquiera conoce, a pesar de todo. <\/li>\n\n\n\n<li>El tiempo de la mujer es precioso, si te concede salir contigo debes ofrecerle la cena. Lo que me hace bastante gracia, considerando que jefes de empresa pagan 1.000,00 \u20ac la hora por hablar conmigo.  <\/li>\n<\/ul>\n\n<p>Yo soy m\u00e1s de un modelo de coinversi\u00f3n, donde dos personas (independientemente del sexo) donan ambas tiempo y recursos en el deseo de conocer a la otra persona. En general prefiero empezar con un aperitivo, solo para no encontrarme bloqueado una noche con una persona que quiz\u00e1s ni siquiera me gusta, para luego volver a quedar para cenar (fuera o en mi casa). Claramente invito yo, pero porque soy yo quien invita, no porque sea hombre.  <\/p>\n\n<p>Dicho esto, me conoc\u00e9is: sab\u00e9is que me encanta de vez en cuando hacer lo contrario de lo que creo, para probar matices diferentes de la realidad o por diversi\u00f3n. He entendido c\u00f3mo piensa la Bond Girl, as\u00ed que con ella voy <em>a tope<\/em> en un modelo totalmente opuesto al m\u00edo. Seguir\u00e9 el <em>Cicisbeo Game<\/em>, siguiendo la estela del caballero sirviente del siglo XVIII que asist\u00eda a la noble dama casada en las tareas personales (aseo, correspondencia, compras, visitas).  <\/p>\n\n<p>Voy a recogerla a la puerta de su casa. Obviamente llega tarde, as\u00ed que me pongo en Youtube a ver v\u00eddeos de Gigi Proietti. Y mientras me r\u00edo con fervor pantagru\u00e9lico llega ella. Me giro, \u00a1joder, qu\u00e9 guapa!   <\/p>\n<div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/media2.giphy.com\/media\/v1.Y2lkPTc5MGI3NjExMnYxNmh1YWo5c3Y0amIxdTg3NzZjMjE3ZXZvaHk3eDBhMXN5ajhrbyZlcD12MV9pbnRlcm5hbF9naWZfYnlfaWQmY3Q9Zw\/YlPeYXasYEPpC\/giphy.gif\" alt=\"Imagen del relato de la Bond Girl y el cicisbeo\" style=\"aspect-ratio:1;width:278px;height:auto\"\/><figcaption class=\"wp-element-caption\">\u00a1Mi reacci\u00f3n nada m\u00e1s verla!<\/figcaption><\/figure>\n<\/div>\n<p><br\/>Est\u00e1 incre\u00edblemente elegante, vestida con un vestido muy particular, de grand\u00edsimo estilo, que combina adornos l\u00fadicos con l\u00edneas esenciales y serias. La mirada es como la de un lago alpino: helad\u00edsima, pura, profunda. Muy particular: distante, como si enfocara a dos metros y medio detr\u00e1s de tu cabeza. Te mira, pero es como si no te mirara, como si estuviera en otra parte. Esto le confiere una expresi\u00f3n hier\u00e1tica, de quien percibe la dimensi\u00f3n oculta de la existencia, un puente hacia otro mundo, distante y m\u00edstico.<br\/>Y tambi\u00e9n est\u00e1 <em>buena<\/em>: bajo los adornos del vestido, se vislumbra un f\u00edsico tonificado.    <\/p>\n\n<h2 class=\"wp-block-heading\">El esp\u00eda en el restaurante<\/h2>\n\n<p>Cicisbeicamente salgo del coche para saludarla y abrirle la puerta. Su belleza me quita el aliento y me comprime el pecho. Me esfuerzo por fingir que no pasa nada, hablo con ella de lo que sea y la llevo a un restaurante cerca de casa.  <\/p>\n\n<p>La escena de siempre, ella entra, los camareros se sobresaltan, nos dan la mejor mesa, todas las miradas son para ella. Nos contamos nuestras vidas. Ella est\u00e1 acostumbrada a hombres que intentan impresionarla, yo hago lo contrario: intento que se califique, para entender si tiene caracter\u00edsticas interesantes para m\u00ed m\u00e1s all\u00e1 de la belleza. Al mismo tiempo hablo de mis debilidades, de mis momentos dif\u00edciles, de las cosas que a\u00fan tengo que mejorar. De manera siempre ligera, aut\u00e9ntica, bromeando bastante. Ella se abre y empieza a hablar de sus dificultades. Se siente sola, no consigue encontrar un hombre que le guste de verdad. Tiene poca estima por los hombres italianos: prometen mares y monta\u00f1as con palabras, pero en los hechos tienen muy pocas atenciones.<br\/>Le pregunto cu\u00e1ntas veces le ha pasado encontrarse mal con el macho it\u00e1lico. Me dice que muchas veces.<br\/>&#8220;<em>Eh, entonces el problema no son los hombres, eres t\u00fa<\/em>&#8220;.        <\/p>\n\n<p>Me mira intrigada.<br\/>&#8220;<em>La primera vez puede ser mala suerte. La segunda, casualidad. Pero si a la tercera, cuarta, quinta vez&#8230; si todos los hombres que encuentras son equivocados\u2026 no puede ser mala suerte. Eres t\u00fa quien est\u00e1 haciendo algo mal&#8221;   <\/em>.<br\/>Finalmente su mirada me enfoca a m\u00ed. Me mira. Me ve. Est\u00e1 ah\u00ed conmigo.   <\/p>\n\n<p>Insisto &#8220;<em>Mira, aqu\u00ed hay un tema cultural. Sigues esperando un cortejo de hombre del este, olvidando que vives en Italia.  Si un hombre le regalara 50 rosas a una mujer espa\u00f1ola reci\u00e9n conocida, ella pensar\u00eda de \u00e9l: <\/em><\/p>\n\n<ul class=\"wp-block-list\">\n<li><em>que es un pringado;<\/em><\/li>\n\n\n\n<li><em>que necesita pagar\/comprar a una mujer para estar con ella;<\/em><\/li>\n\n\n\n<li><em>que es un hombre de bajo valor y con pocas alternativas.<\/em><\/li>\n<\/ul>\n\n<p><em>Adem\u00e1s, la mujer se sentir\u00eda ofendida, objetificada, como si el hombre quisiera comprarla. Y el gesto le parecer\u00eda poco sincero: un hombre italiano no le regala 50 rosas si no es en el aniversario y despu\u00e9s de 5 a\u00f1os de matrimonio.&#8221; <\/em><\/p>\n\n<p>Ella entiende, pero le cuesta moverse del modelo de hombre con el que ha crecido. <\/p>\n\n<p>Su mirada ahora es diferente: me mira con complicidad y atracci\u00f3n. Est\u00e1 ah\u00ed conmigo, presente, vulnerable y potente. Estas t\u00edas son todas iguales: basta con que las trates por lo que son, &#8211; es decir, personas normal\u00edsimas como otras &#8211; basta con que les plantes cara, les hagas notar amablemente las gilipolleces que dicen (con el mismo tono afectuoso y burl\u00f3n que tendr\u00edas con tu hermana peque\u00f1a) y\u2026 ellas bajan del pedestal y se encienden por ti.<br\/>Me levanto y me siento a su lado, la mimo y la acaricio mientras me burlo un poco de ella.  <\/p>\n\n<p>Se abre a\u00fan m\u00e1s. Me cuenta que durante m\u00e1s de un a\u00f1o ha hecho&#8230; de ESP\u00cdA. <\/p>\n<div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/media4.giphy.com\/media\/v1.Y2lkPTc5MGI3NjExb3AwMmVyZmVheHpsMWtvOXZkZzZ5YWR5Z2J0YTliajBrMXp0ZWN3bCZlcD12MV9pbnRlcm5hbF9naWZfYnlfaWQmY3Q9Zw\/t3dLl0TGHCxTG\/giphy.gif\" alt=\"Imagen del relato de la Bond Girl y el cicisbeo\" style=\"aspect-ratio:1;width:258px;height:auto\"\/><figcaption class=\"wp-element-caption\">\u00a1Yo cuando me cuenta sus aventuras de chica Bond!<\/figcaption><\/figure>\n<\/div>\n<p><br\/>S\u00ed, mientras estaba en Suecia ha colaborado con la inteligencia local para sonsacar informaci\u00f3n a sujetos sensibles. Normalmente la considerar\u00eda una probable tonter\u00eda, pero me da detalles y es muy cre\u00edble: en el fondo, de todas las personas que conozco, ella es lo m\u00e1s parecido a una chica Bond. Me cuenta alguna aventura, no much\u00edsimo, pero&#8230; querido lector, no puedo contarte nada. \u00bfAcaso quieres que los pr\u00f3ximos art\u00edculos est\u00e9n escritos desde detr\u00e1s de las rejas?<br\/>Es simp\u00e1tica y divertida, le digo que &#8211; en caso de que se creara qu\u00edmica &#8211; me gustar\u00eda llevarla en barco conmigo a Cerde\u00f1a, a finales de agosto. <\/p>\n\n<h2 class=\"wp-block-heading\">Las rosas y el rechazo<\/h2>\n\n<p>Re\u00edmos y bromeamos. Somos la \u00faltima pareja del restaurante. La invito a tomar algo en mi casa, pero ella rechaza, aduciendo como raz\u00f3n &#8221;  <em>me conozco, una vez que est\u00e9 en tu casa, no me contendr\u00eda. Prefiero que nos conozcamos antes <\/em>&#8220;.<\/p>\n\n<p>Vale, lo entiendo. La tensi\u00f3n sexual corta el aire, pero la acompa\u00f1o a casa, charlando amablemente. Me hace escuchar algunos de sus temas en Spotify, sus producciones art\u00edsticas creadas sampleando las frases colmadas de deseo que los hombres le mandan por WhatsApp. Una cosa a lo Magnifico, en efecto&#8230; no puedo sino apreciarlo. \u00a1Pero confieso que siento celos por estos muertos de co\u00f1o que coquetean con mi bond girl!    <\/p>\n\n<p>De vuelta se me ocurre una idea: demos un paso en su direcci\u00f3n, regal\u00e9mosle unas rosas, qui\u00e9n sabe si entiende finalmente que hay que venir ambos al encuentro.<br\/>Reservo 50 rosas precios\u00edsimas, de esas estabilizadas, para que se las entreguen en casa, con una tarjeta que reza:<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Recordatorio perfumado de tres instantes: <br\/>mi toque ligero sobre tu piel; <br\/>tu mirada, verdadera, desvelada, intensa, concedida a poqu\u00edsimos, clavada en la m\u00eda; <br\/>el resto del mundo que se desvanec\u00eda.<\/p>\n<\/blockquote>\n<div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"623\" height=\"1024\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.28.50-623x1024.png\" alt=\"Captura de conversaci&#xF3;n con la Bond Girl\" class=\"wp-image-2021\" style=\"width:373px;height:auto\" srcset=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.28.50-623x1024.png 623w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.28.50-182x300.png 182w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.28.50-720x1184.png 720w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.28.50-580x954.png 580w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.28.50-320x526.png 320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.28.50.png 766w\" sizes=\"auto, (max-width: 623px) 100vw, 623px\" \/><\/figure>\n<\/div>\n<p>Al d\u00eda siguiente recibe las rosas, me escribe toda contenta y anticipa la cena que deber\u00edamos habernos hecho juntos.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"594\" height=\"1024\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.24.36-594x1024.png\" alt=\"Captura de conversaci&#xF3;n con la Bond Girl\" class=\"wp-image-2022\" style=\"width:382px;height:auto\" srcset=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.24.36-594x1024.png 594w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.24.36-174x300.png 174w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.24.36-768x1325.png 768w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.24.36-720x1242.png 720w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.24.36-580x1000.png 580w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.24.36-320x552.png 320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.24.36.png 770w\" sizes=\"auto, (max-width: 594px) 100vw, 594px\" \/><\/figure>\n<\/div>\n<p>Despu\u00e9s de este paso en su direcci\u00f3n, me espero un paso suyo en la m\u00eda. En particular, querr\u00eda que viniera a cenar a mi casa. No porque necesariamente tengamos que follar, sino porque quiero un lugar \u00edntimo en el que conocerla mejor, sin camareros y clientes varios. Un lugar donde mimarla, en el sof\u00e1, con una copa en la mano.   <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"666\" height=\"1024\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.24.16-666x1024.png\" alt=\"Captura de conversaci&#xF3;n con la Bond Girl\" class=\"wp-image-2024\" style=\"width:406px;height:auto\" srcset=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.24.16-666x1024.png 666w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.24.16-195x300.png 195w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.24.16-768x1181.png 768w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.24.16-720x1107.png 720w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.24.16-580x892.png 580w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.24.16-320x492.png 320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.24.16.png 796w\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" \/><\/figure>\n<\/div>\n<p>\u00a1Ni de co\u00f1a! &#8220;<em>Yo esas cosas no las hago<\/em>&#8220;.<br\/>Sinceramente, esta falta de confianza me molesta. Me hace sentir rechazado.  En fin, buscar\u00e9 un restaurante de pescado lo m\u00e1s lejos posible de mi casa. <br\/>Como Barney de HIMYM, yo tambi\u00e9n tengo un tipo para cada cosa. Para los restaurantes, mi tipo es mi querido socio Tommi: un estiloso lord de la mil\u00e1n bien, amante de los placeres de la mesa, de la elegancia y de la convivencia.  <br\/>Lo bueno de Tommi es que puedes hacerle las peticiones m\u00e1s absurdas, combinando presupuesto, ubicaci\u00f3n, calidad de la cocina y zona&#8230; \u00e9l siempre tendr\u00e1 tres restaurantes excelentes para recomendarte. Le doy un brief preciso: Excelente pescado, en la zona de Isola, aspecto no pretencioso, sino incluso humilde, un poco polvoriento y asequible. \u00bfNo vienes a mi casa? Yo elijo un restaurante casero y familiar.   <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"586\" height=\"1024\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3570-1-586x1024.jpg\" alt=\"Foto personal del relato de la Bond Girl y el cicisbeo\" class=\"wp-image-2026\" style=\"width:423px;height:auto\" srcset=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3570-1-586x1024.jpg 586w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3570-1-172x300.jpg 172w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3570-1-768x1341.jpg 768w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3570-1-880x1536.jpg 880w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3570-1-1173x2048.jpg 1173w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3570-1-720x1257.jpg 720w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3570-1-580x1013.jpg 580w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3570-1-320x559.jpg 320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3570-1.jpg 1320w\" sizes=\"auto, (max-width: 586px) 100vw, 586px\" \/><\/figure>\n<\/div><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"634\" height=\"1024\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3571-634x1024.jpg\" alt=\"Foto personal del relato de la Bond Girl y el cicisbeo\" class=\"wp-image-2027\" style=\"width:428px;height:auto\" srcset=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3571-634x1024.jpg 634w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3571-186x300.jpg 186w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3571-768x1240.jpg 768w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3571-951x1536.jpg 951w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3571-1268x2048.jpg 1268w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3571-720x1163.jpg 720w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3571-580x937.jpg 580w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3571-320x517.jpg 320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3571.jpg 1320w\" sizes=\"auto, (max-width: 634px) 100vw, 634px\" \/><\/figure>\n<\/div><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"711\" height=\"1024\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3572-2-711x1024.jpg\" alt=\"Foto personal del relato de la Bond Girl y el cicisbeo\" class=\"wp-image-2030\" style=\"width:415px;height:auto\" srcset=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3572-2-711x1024.jpg 711w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3572-2-208x300.jpg 208w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3572-2-768x1107.jpg 768w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3572-2-1066x1536.jpg 1066w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3572-2-720x1037.jpg 720w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3572-2-580x836.jpg 580w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3572-2-320x461.jpg 320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/IMG_3572-2.jpg 1320w\" sizes=\"auto, (max-width: 711px) 100vw, 711px\" \/><\/figure>\n<\/div>\n<p>Pasamos una buena velada. Terminada la cena, la acompa\u00f1o enseguida a casa. Le gustar\u00eda tomar algo en alg\u00fan sitio, pero yo estoy cansado.<br\/>Al d\u00eda siguiente me escribe, estoy fr\u00edo y distante, un poco molesto.<br\/>Intenta llamar mi atenci\u00f3n. Publica la historia con las rosas. Me escribe que no puede dejar de admirarlas. Aprovecho para aclarar mi posici\u00f3n sobre la coinversi\u00f3n necesaria en la fase de conocimiento:     <\/p>\n\n<figure class=\"wp-block-image size-large is-resized is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"784\" height=\"1024\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.50.52-784x1024.png\" alt=\"Captura de conversaci&#xF3;n con la Bond Girl\" class=\"wp-image-2033\" style=\"width:682px;height:auto\" srcset=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.50.52-784x1024.png 784w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.50.52-230x300.png 230w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.50.52-768x1004.png 768w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.50.52-720x941.png 720w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.50.52-580x758.png 580w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.50.52-320x418.png 320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-13.50.52.png 1134w\" sizes=\"auto, (max-width: 784px) 100vw, 784px\" \/><\/figure>\n\n<p>Vabb\u00e9, mi amiga Lella dir\u00eda quiz\u00e1s que he sido un poco hist\u00e9rico. Sigo convencido de mis posiciones. <\/p>\n\n<h2 class=\"wp-block-heading\">Adi\u00f3s, chica Bond<\/h2>\n\n<p>La vuelvo a invitar una tercera noche. Le pregunto si prefiere fuera o en casa.  Obviamente prefiere fuera, as\u00ed &#8220;podemos disfrutar de la velada sin pensar en los platos que hay que fregar&#8221;. <br\/>S\u00ed, los platos&#8230; \u00a1y de todos modos tengo el lavavajillas y la asistenta! Pero bueno. <\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"255\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-14.41.37-1024x255.png\" alt=\"Captura de conversaci&#xF3;n con la Bond Girl\" class=\"wp-image-2035\" srcset=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-14.41.37-1024x255.png 1024w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-14.41.37-300x75.png 300w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-14.41.37-768x191.png 768w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-14.41.37-720x179.png 720w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-14.41.37-580x144.png 580w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-14.41.37-320x80.png 320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-14.41.37.png 1118w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p>Casualmente un compromiso de trabajo me obliga a anular la cena.<br\/>Espera una nueva invitaci\u00f3n m\u00eda.<br\/>No llega.<br\/>Me vuelve a contactar, hablamos de lo m\u00e1s banal, y finalmente me pregunta qu\u00e9 he decidido hacer para las vacaciones.<br\/>Y aqu\u00ed sale todo el siciliano que hay en m\u00ed:<\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"966\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-14.43.07-1024x966.png\" alt=\"Captura de conversaci&#xF3;n con la Bond Girl\" class=\"wp-image-2036\" srcset=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-14.43.07-1024x966.png 1024w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-14.43.07-300x283.png 300w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-14.43.07-768x725.png 768w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-14.43.07-720x680.png 720w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-14.43.07-580x547.png 580w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-14.43.07-320x302.png 320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-13-alle-14.43.07.png 1138w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p>yo: &#8220;Me voy en barco. Pero claramente ni siquiera te lo propongo: si es demasiado pronto para ir a cenar a mi casa, imag\u00ednate ir de vacaciones juntos&#8221;.<br\/>ella: no, no, el barco est\u00e1 bien, la casa no.<\/p>\n\n<p>\u00a1S\u00ed, ni de co\u00f1a!<br\/>A estas alturas, casi cualquiera habr\u00eda insistido un poco en verla, foll\u00e1rsela y luego desaparecer.<br\/>Pero yo no tengo ganas de perder el tiempo y no follo\/inicio relaciones con chicas con las que no comparto los valores.<\/p>\n\n<p>\u00a1Adi\u00f3s, Bond Girl! La vida es demasiado corta para perder el tiempo contigo.<br\/>\u00a1Nextada! <\/p>\n\n<p class=\"has-text-align-center\"><br\/><\/p>\n\n<figure class=\"wp-block-image size-large is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"837\" height=\"1024\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Gemini_Generated_Image_w6ipaaw6ipaaw6ip-837x1024.png\" alt=\"Ilustraci&#xF3;n final del relato de la Bond Girl\" class=\"wp-image-3945\" srcset=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Gemini_Generated_Image_w6ipaaw6ipaaw6ip-837x1024.png 837w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Gemini_Generated_Image_w6ipaaw6ipaaw6ip-245x300.png 245w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Gemini_Generated_Image_w6ipaaw6ipaaw6ip-768x940.png 768w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Gemini_Generated_Image_w6ipaaw6ipaaw6ip-1255x1536.png 1255w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Gemini_Generated_Image_w6ipaaw6ipaaw6ip-1673x2048.png 1673w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Gemini_Generated_Image_w6ipaaw6ipaaw6ip-720x881.png 720w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Gemini_Generated_Image_w6ipaaw6ipaaw6ip-580x710.png 580w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Gemini_Generated_Image_w6ipaaw6ipaaw6ip-320x392.png 320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Gemini_Generated_Image_w6ipaaw6ipaaw6ip-1320x1616.png 1320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2025\/08\/Gemini_Generated_Image_w6ipaaw6ipaaw6ip.png 1856w\" sizes=\"auto, (max-width: 837px) 100vw, 837px\" \/><\/figure>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><!--Yasr Visitor Votes Shortcode--><div id='yasr_visitor_votes_66cd9a959d781' class='yasr-visitor-votes'><div class=\"yasr-custom-text-vv-before yasr-custom-text-vv-before-3750\">Click to rate this post!<\/div><div id='yasr-vv-second-row-container-66cd9a959d781'\r\n                                        class='yasr-vv-second-row-container'><div id='yasr-visitor-votes-rater-66cd9a959d781'\r\n                                      class='yasr-rater-stars-vv'\r\n                                      data-rater-postid='3750'\r\n                                      data-rating='0'\r\n                                      data-rater-starsize='24'\r\n                                      data-rater-readonly='false'\r\n                                      data-rater-nonce='3cd8c05a83'\r\n                                      data-issingular='false'\r\n                                    ><\/div><div class=\"yasr-vv-stats-text-container\" id=\"yasr-vv-stats-text-container-66cd9a959d781\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\"\r\n                                   class=\"yasr-dashicons-visitor-stats\"\r\n                                   data-postid=\"3750\"\r\n                                   id=\"yasr-stats-dashicon-66cd9a959d781\">\r\n                                   <path d=\"M18 18v-16h-4v16h4zM12 18v-11h-4v11h4zM6 18v-8h-4v8h4z\"><\/path>\r\n                               <\/svg><span id=\"yasr-vv-text-container-66cd9a959d781\" class=\"yasr-vv-text-container\">[Total: <span id=\"yasr-vv-votes-number-container-66cd9a959d781\">0<\/span>  Average: <span id=\"yasr-vv-average-container-66cd9a959d781\">0<\/span>]<\/span><\/div><div id='yasr-vv-loader-66cd9a959d781' class='yasr-vv-container-loader'><\/div><\/div><div id='yasr-vv-bottom-container-66cd9a959d781'\r\n                              class='yasr-vv-bottom-container'\r\n                              style='display:none'><\/div><\/div><!--End Yasr Visitor Votes Shortcode--><\/div>","protected":false},"excerpt":{"rendered":"<p>Click to rate this post! [Total: 0 Average: 0] \u00daltimamente en Tinder se encuentra de todo. \u00a1Incluso esp\u00edas! Durante mis cl\u00e1sicos 5 minutos diarios de swipe, me llama la atenci\u00f3n su perfil. Tiene la piel muy clara, el pelo negr\u00edsimo, ojos claros, de un tono desva\u00eddo entre el verde y el azul. 26 a\u00f1os, declara [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3949,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[82],"tags":[142,217,238],"class_list":["post-3750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reporte","tag-chica-bond","tag-dating-milan","tag-tinder-espana"],"featured_image_urls_v2":{"full":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e.png",1792,2368,false],"thumbnail":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-150x150.png",150,150,true],"medium":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-227x300.png",227,300,true],"medium_large":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-768x1015.png",720,952,true],"large":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-775x1024.png",720,951,true],"1536x1536":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-1162x1536.png",1162,1536,true],"2048x2048":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-1550x2048.png",1550,2048,true],"typology-cover":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e.png",1792,2368,false],"typology-a":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-720x951.png",720,951,true],"typology-b":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-580x766.png",580,766,true],"typology-c":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-320x423.png",320,423,true],"mailpoet_newsletter_max":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2019\/01\/Gemini_Generated_Image_uv8e7iuv8e7iuv8e-1320x1744.png",1320,1744,true]},"post_excerpt_stackable_v2":"<p>Click to rate this post! [Total: 0 Average: 0] \u00daltimamente en Tinder se encuentra de todo. \u00a1Incluso esp\u00edas! Durante mis cl\u00e1sicos 5 minutos diarios de swipe, me llama la atenci\u00f3n su perfil. Tiene la piel muy clara, el pelo negr\u00edsimo, ojos claros, de un tono desva\u00eddo entre el verde y el azul. 26 a\u00f1os, declara que busca una relaci\u00f3n seria.Rasgos de mujer del Este, con p\u00f3mulos marcados y mand\u00edbula importante. No la t\u00edpica mu\u00f1eca de adorno, sino una mujer que puede ganar Miss Ucrania y arrancarte el esternocleidomastoideo con un movimiento de Krav Maga.Las fotos tienen un gusto exquisito, como\u2026<\/p>\n","category_list_v2":"<a href=\"https:\/\/tiredofboys.com\/es\/category\/reporte\/\" rel=\"category tag\">Reporte<\/a>","author_info_v2":{"name":"MagniFico","url":"https:\/\/tiredofboys.com\/es\/author\/magnifico\/"},"comments_num_v2":"0 comments","yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/posts\/3750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/comments?post=3750"}],"version-history":[{"count":6,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/posts\/3750\/revisions"}],"predecessor-version":[{"id":6348,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/posts\/3750\/revisions\/6348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/media\/3949"}],"wp:attachment":[{"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/media?parent=3750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/categories?post=3750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/tags?post=3750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}