{"id":3553,"date":"2020-12-22T23:50:34","date_gmt":"2020-12-22T22:50:34","guid":{"rendered":"https:\/\/tiredofboys.com\/amar-es-dejar-ir-a-uno-mismo-a-la-otra-persona-a-los-propios-limites\/"},"modified":"2026-04-10T02:04:19","modified_gmt":"2026-04-10T01:04:19","slug":"amar-es-dejar-ir-a-uno-mismo-a-la-otra-persona-a-los-propios-limites","status":"publish","type":"post","link":"https:\/\/tiredofboys.com\/es\/amar-es-dejar-ir-a-uno-mismo-a-la-otra-persona-a-los-propios-limites\/","title":{"rendered":"Amar es dejar ir: a uno mismo, a la otra persona, a los propios l\u00edmites."},"content":{"rendered":"<div style='text-align:center' class='yasr-auto-insert-visitor'><!--Yasr Visitor Votes Shortcode--><div id='yasr_visitor_votes_a560ca876dda2' class='yasr-visitor-votes'><div class=\"yasr-custom-text-vv-before yasr-custom-text-vv-before-3553\">Click to rate this post!<\/div><div id='yasr-vv-second-row-container-a560ca876dda2'\r\n                                        class='yasr-vv-second-row-container'><div id='yasr-visitor-votes-rater-a560ca876dda2'\r\n                                      class='yasr-rater-stars-vv'\r\n                                      data-rater-postid='3553'\r\n                                      data-rating='0'\r\n                                      data-rater-starsize='24'\r\n                                      data-rater-readonly='false'\r\n                                      data-rater-nonce='3cd8c05a83'\r\n                                      data-issingular='false'\r\n                                    ><\/div><div class=\"yasr-vv-stats-text-container\" id=\"yasr-vv-stats-text-container-a560ca876dda2\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\"\r\n                                   class=\"yasr-dashicons-visitor-stats\"\r\n                                   data-postid=\"3553\"\r\n                                   id=\"yasr-stats-dashicon-a560ca876dda2\">\r\n                                   <path d=\"M18 18v-16h-4v16h4zM12 18v-11h-4v11h4zM6 18v-8h-4v8h4z\"><\/path>\r\n                               <\/svg><span id=\"yasr-vv-text-container-a560ca876dda2\" class=\"yasr-vv-text-container\">[Total: <span id=\"yasr-vv-votes-number-container-a560ca876dda2\">0<\/span>  Average: <span id=\"yasr-vv-average-container-a560ca876dda2\">0<\/span>]<\/span><\/div><div id='yasr-vv-loader-a560ca876dda2' class='yasr-vv-container-loader'><\/div><\/div><div id='yasr-vv-bottom-container-a560ca876dda2'\r\n                              class='yasr-vv-bottom-container'\r\n                              style='display:none'><\/div><\/div><!--End Yasr Visitor Votes Shortcode--><\/div>\n<p>23:35, Mil\u00e1n.<br\/>Han transcurrido 8 horas y 50 minutos desde que le volv\u00ed a escribir a <a href=\"https:\/\/tiredofboys.com\/report\/bimba-zoccola-ecco-come-ho-impiegato-20-anni-per-trovare-amore-e-2-settimane-per-perderlo-per-sempre\/\" data-type=\"post\" data-id=\"107\">la Americanina<\/a>, la chica por la que hab\u00eda perdido la cabeza.<br\/>Dos meses y 27 d\u00edas desde su \u00faltimo mensaje.<br\/><strong>Dos meses y 24 d\u00edas desde mi \u00faltimo intento de hablar con ella<\/strong>. <br\/><\/p>\n<div class=\"wp-block-image is-resized is-style-rounded\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"954\" src=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07-1024x954.png\" alt=\"Imagen evocadora para el relato Amar y dejar ir\" class=\"wp-image-1327\" srcset=\"https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07-1024x954.png 1024w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07-300x279.png 300w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07-768x715.png 768w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07-720x671.png 720w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07-580x540.png 580w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07-320x298.png 320w, https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07.png 1314w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p>\u00bfPoco? \u00bfMucho? El tiempo es ef\u00edmero o eterno, denso o enrarecido, seg\u00fan la intensidad con la que lo vivas.<br\/>Para m\u00ed, estos dos meses y 24 d\u00edas han sido como una condena cumplida \u00edntegramente por un delito de mediana entidad.<br\/>Dos meses y 24 d\u00edas en los que he sufrido bastante, como nunca en mi vida.<br\/>Dos meses y 24 d\u00edas en los que he resistido con todas mis fuerzas el impulso de sentirla, buscarla, escribirle. Un poco por respetar su voluntad y no pasar por acosador.   <br\/><strong>Pero sobre todo para no causar desastres.<\/strong><\/p>\n\n<p>\u00bfPor qu\u00e9 desastres?<br\/>Puede pasar que te enamores, que pierdas la cabeza, incluso que caigas rendido. <br\/><strong>Pero supongamos que la otra persona no est\u00e1 (ya) interesada. <\/strong><br\/>Supongamos que se da cuenta de que no forma un buen equipo contigo. <br\/>Supongamos que al final busc\u00e1is cosas diferentes, que para ella t\u00fa has sido la distracci\u00f3n de un momento, mientras que para ti ella era el sue\u00f1o de una vida diferente.<\/p>\n\n<p>Si te das cuenta de esto y sigues as\u00ed&#8230; bueno, <strong>el enamoramiento est\u00e1 derivando en obsesi\u00f3n<\/strong>.<\/p>\n\n<h2 class=\"wp-block-heading\">Amar significa saber dejar ir.<\/h2>\n\n<p>F\u00e1cil de decir, pero&#8230; para m\u00ed ha sido una pesadilla lograrlo.<br\/>En los \u00faltimos 3 meses, he pensado infinitas veces en escribirle. <strong>He redactado una docena de mensajes diferentes.<\/strong> He tenido la inteligencia de darme una regla: antes de enviarlo, debe pasar por el filtro de mis amigos\/coach\/consejeros. En resumen, debe ser le\u00eddo por una mirada externa y sana.<br\/>Yo escrib\u00eda, ellos lo descartaban todo y me indicaban los problemas en los que ten\u00eda que trabajar. Es decir: qu\u00e9 situaciones sin resolver generaban este apego hacia una persona objetivamente no interesada en m\u00ed.  <br\/><strong>Yo trabajaba en ello, durante d\u00edas y d\u00edas. <\/strong>Reescrib\u00eda el mensaje, lo enviaba para su aprobaci\u00f3n, mientras tanto cargaba el equipaje en el coche para ir a ver a la americanina, seguro de que no podr\u00eda hacer otra cosa que recibirme con los brazos abiertos y&#8230; ellos me lo descartaban. <br\/>Y descarga el coche, trabaja en el bloqueo, reescribe, env\u00eda para su aprobaci\u00f3n, recarga el coche, espera el ok y&#8230; nada, no est\u00e1 bien. Descarga estas putas maletas, trabaja en el problema profundo, reescribe este puto mensaje, env\u00eda para su aprobaci\u00f3n, lanza las maletas al maletero y&#8230; \u00bfadivina? Todo por rehacer.<br\/>En la pr\u00e1ctica, hay quien hace ejercicio levantando pesas de 160 kg y quien, en cambio, carga y descarga maletas.  <\/p>\n\n<h2 class=\"wp-block-heading\">El equipaje emocional<\/h2>\n\n<p>Obviamente, la maleta <strong>es una met\u00e1fora del peso emocional que llevaba conmigo y que he tenido que dejar ir<\/strong>, para ser libre de dejar ir el recuerdo de ella.<\/p>\n\n<p>Si no eres capaz de dejar ir, no es porque est\u00e9s enamorado de la otra persona, sino porque la situaci\u00f3n\/la persona te hace resonar bloqueos profundos. <strong>Alimenta y sacia a los monstruos que tienes dentro. <\/strong>O, como se dice en Mil\u00e1n, &#8220;te triggera los bloqueos del Inner Game&#8221; (s\u00ed, en Mil\u00e1n hablan as\u00ed, \u00a1fiigaaa!).<\/p>\n\n<p><strong>Yo he vivido 20 a\u00f1os sin que nada me rozase de verdad<\/strong>, detr\u00e1s de las protecciones y los sistemas de defensa que hab\u00eda construido.<br\/>Podr\u00eda haber vivido otros 20 a\u00f1os as\u00ed, sin darme cuenta. Quiz\u00e1s toda la vida. <\/p>\n\n<p>Luego lleg\u00f3 <em>ella<\/em>: la tormenta perfecta. La Americanina activ\u00f3 mis 2 bloqueos profundos y&#8230; <strong><em>\u00a1sboom!<\/em> He explotado<\/strong>. Empec\u00e9 a comportarme de una manera que para m\u00ed no ten\u00eda sentido, sin la posibilidad de entender el porqu\u00e9.  <\/p>\n\n<p>Volver a contactarla antes de haber resuelto esta cuesti\u00f3n solo habr\u00eda llevado a desastres.<\/p>\n\n<h2 class=\"wp-block-heading\">algo ha cambiado<\/h2>\n\n<p>Bueno, vamos al d\u00eda de hoy.<br\/><strong>Esta ma\u00f1ana he escrito el mensaje.<\/strong><br\/>Lo he hecho como ejercicio, sin sentir ya la necesidad de contactarla.<br\/>He escrito esto.<\/p>\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"has-typology-acc-color has-text-color\" id=\"block-e5a319d0-f1d4-4d13-b475-b2673a9cb21f\"><em>Hola [X],<br\/>en estos tres meses te he echado much\u00edsimo de menos. No hay d\u00eda en que no te haya pensado y no haya deseado hablarte, besarte, tenerte conmigo.  <br\/>La verdad es que he entendido lentamente una cosa, mientras habl\u00e1bamos hasta tarde por la noche en el paseo mar\u00edtimo de Zadar, mientras manten\u00eda la mano sobre tus muslos intentando matar ciclistas a escondidas, mientras corr\u00edamos de Dubrovnik al hotel porque no consegu\u00edamos contenernos de follar.<br\/><br\/>He entendido que me hab\u00eda enamorado de ti.<br\/> <br\/>Cuando me acariciabas el pelo mientras conduc\u00eda, o cuando te fotografiaba mientras te trepabas como una monita, en mi interior dec\u00eda: \u201c\u00a1La amo, joder!\u201d.<br\/><br\/>Esto me asust\u00f3 bastante: no me pasaba desde hace 20 a\u00f1os, me sent\u00eda inerme y sin control, me aterraba poner en manos de otra persona el poder de hacerme sufrir.<br\/>En mi pasado hab\u00eda asociado las relaciones al sufrimiento y a la falta de libertad. Puedes imaginarte lo que ha significado para m\u00ed descubrir que me hab\u00eda enamorado de una chica a la que le hab\u00eda prometido cero compromisos, libertad y una relaci\u00f3n ligera.  Una chica que me hab\u00eda elegido porque no quer\u00eda sentirse atada. <br\/>No era capaz de gestionar emociones tan fuertes. En realidad, ni siquiera estoy seguro de poder hacerlo ahora. <br\/><br\/>\u00bfPor qu\u00e9 no te lo he dicho?<br\/>Porque ten\u00eda miedo de perderte. Ten\u00eda miedo de que desaparecieras de mi vida, priv\u00e1ndome de esta nueva droga que necesitaba.<br\/>He intentado a menudo volver a mi imagen\/m\u00e1scara de persona fuerte, decidida, due\u00f1a de s\u00ed misma \u2014incluso haciendo el capullo a veces\u2026\u2014 <\/em> <em>  hoy releo esos mensajes y pienso: \u201cQu\u00e9 pena no haberme mostrado \u00edntegramente\u201d.<br\/><br\/>No me juzgo. Es<\/em> <em>ha sido un momento dif\u00edcil, bello y doloroso. Me he sentido como un ciego que finalmente ha visto la luz, despu\u00e9s de una vida pasada a oscuras. <br\/> <br\/>Pero te echo de menos. Echo de menos las caras raras que pon\u00edas, echo de menos tu sonrisa, echo de menos despertarme con tus fotos guarras, verte hacer el pino en todas partes, el sabor sofrititoso de tu co\u00f1o, echo de menos darte latigazos mientras te miro con todo el amor del mundo y echo de menos hablar contigo. <br\/><br\/>Piensa que a veces hablo incluso como t\u00fa: \u00abVaccamao\u00bb \u00ab[X]\u00bb<\/em>.<em><br\/><br\/>Te sigo echando de menos, Americanina.<\/em><\/p>\n<\/div><\/div>\n\n<p>Me he mostrado vulnerable, aut\u00e9ntico, sin juicio, sin ni siquiera una petici\u00f3n.<br\/>Bueno, ha llegado la aprobaci\u00f3n (\u00a1estos cabrones!).<br\/>Es m\u00e1s, <strong>por primera vez en la historia, el Coach (Filippo) incluso me ha felicitado<\/strong>:<br\/><\/p>\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"has-typology-acc-color has-text-color\" id=\"block-1e0e9e92-15f1-44e4-8bee-0e4a1cebb719\"><em>Bien hecho. Estoy orgulloso de ti. Es<\/em> <em>ha sido duro, pero lo has conseguido. Brav\u00edsimo. <\/em><br\/><br\/><em>Ten\u00edas esa energ\u00eda emocional del amor que estaba atrapada dentro de ti, y consegu\u00edas hacerla salir solo como forma de juicio y odio. Ahora hemos conseguido hacerla fluir del modo correcto. Ha salido y est\u00e1 bien as\u00ed.  <\/em><br\/><em><br\/>Quiz\u00e1s no responda nunca, pero al final es un buen mensaje, es coherente, tiene sentido, est\u00e1 en Frame LTR\u2026 m\u00e1s de esto no pod\u00edas hacer. Y has hecho tambi\u00e9n 4 meses de trinchera para escribir ese mensaje. T\u00fa la has querido. Le has dado todo. No rindi\u00e9ndote nunca y luchando hasta el final, intentando superar cada dolor, cada inseguridad\u2026 cada obst\u00e1culo que te imped\u00eda ser feliz. A pesar de un dolor lacerante. Te has fiado y has esperado el momento justo, sabiendo que quiz\u00e1s no llegar\u00eda nunca. Manteniendo el dolor contigo, durante meses.       <\/em><br\/><em><br\/>Como sea, lo repito: estoy orgulloso de ti, has hecho un grand\u00edsimo trabajo, has sido realmente bueno. Poqu\u00edsimos est\u00e1n dispuestos a hacer un recorrido as\u00ed. Llegando a este nivel de confianza en el proceso, incluso cuando el sufrimiento te estaba por sobrepasar.<br\/>Responder\u00e1 o no responder\u00e1: no importa. En cualquier caso, lo considero una gran victoria.<br\/>Y si ella no lo entiende\u2026 bueno. Peor para ella. Es   <\/em> <em>solo una est\u00fapida idiota<\/em>.<\/p>\n<\/div><\/div>\n\n<p>Bueno, me he emocionado al leer este mensaje.<br\/>Pero luego me he preguntado:<br\/><strong>&#8220;\u00bfY ahora qu\u00e9 hago? \u00bfLo env\u00edo? \u00bfPero yo quiero todav\u00eda a la Americanina?&#8221;<\/strong>.<\/p>\n\n<p>No lo he pensado mucho. He hecho otra cosa.<br\/>Despu\u00e9s de algunas horas me he dicho: <strong>&#8220;S\u00ed, venga, enviarlo es liberador de todos modos&#8221;.<\/strong> <\/p>\n\n<p>Eso es. Son las 00:38, 9 horas y 53 minutos despu\u00e9s del env\u00edo del mensaje. <\/p>\n\n<p><strong>Ella lo ha visualizado, por la tarde.<\/strong><\/p>\n\n<p><strong>No ha respondido.<\/strong><br\/>No s\u00e9 si responder\u00e1 alguna vez, ni si me gustar\u00e1 lo que dir\u00e1.<\/p>\n\n<p>Pero no me importa.<br\/>Mi estado de \u00e1nimo es tranquilo.<br\/>Me siento ligero. Coraz\u00f3n abierto, mente quieta. <br\/><strong>Me he \u201cliberado\u201d<\/strong> de las cosas no dichas, del juicio hacia ella, de la humillaci\u00f3n y del rechazo.<\/p>\n\n<p>Est\u00e1 claro que me alegrar\u00eda volver a saber de ella, me gustar\u00eda que volviera\u2026 si la cosa tuviera sentido.<br\/>El secreto est\u00e1 todo aqu\u00ed: \u201c<strong>si tuviera sentido<\/strong>\u201d.<\/p>\n\n<p>Con un mensaje as\u00ed, con este nivel de consciencia de la realidad, con los bloqueos resueltos\u2026 todos los escenarios son aceptables. <strong>O vuelves o no vuelves.<\/strong><\/p>\n\n<div class=\"wp-block-group has-typology-bg-color has-typology-acc-background-color has-text-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"has-huge-font-size\">Y, lo que es m\u00e1s importante, no estoy bloqueado en mi vida, o en espera.<\/p>\n\n\n\n<p class=\"has-huge-font-size\">Ahora me voy a la cama y me espero un sue\u00f1o profundo, sereno y reparador.<\/p>\n<\/div><\/div>\n\n<h2 class=\"wp-block-heading\">\u00a1GOLPE DE ESCENA!<\/h2>\n\n<p>Reeditado este post a distancia de cinco a\u00f1os&#8230; bueno, \u00a1la Americanina se ha hecho notar! Lee <a href=\"https:\/\/tiredofboys.com\/report\/americanina-il-ritorno\/\" data-type=\"post\" data-id=\"1060\">aqu\u00ed!<\/a> <\/p>\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\"><\/div><\/div>\n\n\n\n<p class=\"has-huge-font-size\"><\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><!--Yasr Visitor Votes Shortcode--><div id='yasr_visitor_votes_08ea53ac6cd16' class='yasr-visitor-votes'><div class=\"yasr-custom-text-vv-before yasr-custom-text-vv-before-3553\">Click to rate this post!<\/div><div id='yasr-vv-second-row-container-08ea53ac6cd16'\r\n                                        class='yasr-vv-second-row-container'><div id='yasr-visitor-votes-rater-08ea53ac6cd16'\r\n                                      class='yasr-rater-stars-vv'\r\n                                      data-rater-postid='3553'\r\n                                      data-rating='0'\r\n                                      data-rater-starsize='24'\r\n                                      data-rater-readonly='false'\r\n                                      data-rater-nonce='3cd8c05a83'\r\n                                      data-issingular='false'\r\n                                    ><\/div><div class=\"yasr-vv-stats-text-container\" id=\"yasr-vv-stats-text-container-08ea53ac6cd16\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\"\r\n                                   class=\"yasr-dashicons-visitor-stats\"\r\n                                   data-postid=\"3553\"\r\n                                   id=\"yasr-stats-dashicon-08ea53ac6cd16\">\r\n                                   <path d=\"M18 18v-16h-4v16h4zM12 18v-11h-4v11h4zM6 18v-8h-4v8h4z\"><\/path>\r\n                               <\/svg><span id=\"yasr-vv-text-container-08ea53ac6cd16\" class=\"yasr-vv-text-container\">[Total: <span id=\"yasr-vv-votes-number-container-08ea53ac6cd16\">0<\/span>  Average: <span id=\"yasr-vv-average-container-08ea53ac6cd16\">0<\/span>]<\/span><\/div><div id='yasr-vv-loader-08ea53ac6cd16' class='yasr-vv-container-loader'><\/div><\/div><div id='yasr-vv-bottom-container-08ea53ac6cd16'\r\n                              class='yasr-vv-bottom-container'\r\n                              style='display:none'><\/div><\/div><!--End Yasr Visitor Votes Shortcode--><\/div>","protected":false},"excerpt":{"rendered":"<p>Click to rate this post! [Total: 0 Average: 0] 23:35, Mil\u00e1n.Han transcurrido 8 horas y 50 minutos desde que le volv\u00ed a escribir a la Americanina, la chica por la que hab\u00eda perdido la cabeza.Dos meses y 27 d\u00edas desde su \u00faltimo mensaje.Dos meses y 24 d\u00edas desde mi \u00faltimo intento de hablar con ella. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3554,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[83,79,82],"tags":[239,110],"class_list":["post-3553","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-americanina","category-amor","category-reporte","tag-adios","tag-estadounidense"],"featured_image_urls_v2":{"full":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07.png",1314,1224,false],"thumbnail":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07-150x150.png",150,150,true],"medium":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07-300x279.png",300,279,true],"medium_large":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07-768x715.png",720,670,true],"large":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07-1024x954.png",720,671,true],"1536x1536":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07.png",1314,1224,false],"2048x2048":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07.png",1314,1224,false],"typology-cover":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07.png",1314,1224,false],"typology-a":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07-720x671.png",720,671,true],"typology-b":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07-580x540.png",580,540,true],"typology-c":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07-320x298.png",320,298,true],"mailpoet_newsletter_max":["https:\/\/tiredofboys.com\/wp-content\/uploads\/2020\/12\/Schermata-2021-01-10-alle-00.51.07.png",1314,1224,false]},"post_excerpt_stackable_v2":"<p>Click to rate this post! [Total: 0 Average: 0] 23:35, Mil\u00e1n.Han transcurrido 8 horas y 50 minutos desde que le volv\u00ed a escribir a la Americanina, la chica por la que hab\u00eda perdido la cabeza.Dos meses y 27 d\u00edas desde su \u00faltimo mensaje.Dos meses y 24 d\u00edas desde mi \u00faltimo intento de hablar con ella. \u00bfPoco? \u00bfMucho? El tiempo es ef\u00edmero o eterno, denso o enrarecido, seg\u00fan la intensidad con la que lo vivas.Para m\u00ed, estos dos meses y 24 d\u00edas han sido como una condena cumplida \u00edntegramente por un delito de mediana entidad.Dos meses y 24 d\u00edas en los\u2026<\/p>\n","category_list_v2":"<a href=\"https:\/\/tiredofboys.com\/es\/category\/americanina\/\" rel=\"category tag\">Americanina<\/a>, <a href=\"https:\/\/tiredofboys.com\/es\/category\/amor\/\" rel=\"category tag\">Amor<\/a>, <a href=\"https:\/\/tiredofboys.com\/es\/category\/reporte\/\" rel=\"category tag\">Reporte<\/a>","author_info_v2":{"name":"MagniFico","url":"https:\/\/tiredofboys.com\/es\/author\/magnifico\/"},"comments_num_v2":"0 comments","yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/posts\/3553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/comments?post=3553"}],"version-history":[{"count":4,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/posts\/3553\/revisions"}],"predecessor-version":[{"id":6429,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/posts\/3553\/revisions\/6429"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/media\/3554"}],"wp:attachment":[{"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/media?parent=3553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/categories?post=3553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tiredofboys.com\/es\/wp-json\/wp\/v2\/tags?post=3553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}